{"id":411,"count":3,"description":"Centro urbano de estudos e pr\u00e1ticas em S\u00e3o Jos\u00e9 do Rio Preto, SP\r\n<a href=\"https:\/\/cebb.org.br\/en\/praticas-presenciais-regulares-do-cebb-sao-jose-do-rio-preto\/\">Pr\u00e1ticas presenciais<\/a> | <a href=\"https:\/\/cebb.org.br\/en\/praticas-online-regulares-do-cebb-sao-jose-do-rio-preto\/\">Pr\u00e1ticas online<\/a>","link":"https:\/\/cebb.org.br\/en\/category\/centros\/sp\/riopreto\/","name":"CEBB S\u00e3o Jos\u00e9 do Rio Preto","slug":"riopreto","taxonomy":"category","parent":363,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/en\/centros\/sp\/riopreto\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"Centro urbano de estudos e pr\u00e1ticas em S\u00e3o Jos\u00e9 do Rio Preto, SP Pr\u00e1ticas presenciais | Pr\u00e1ticas online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/en\/centros\/sp\/riopreto\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/centros\\\/sp\\\/riopreto\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/centros\\\/sp\\\/riopreto\\\/\",\"name\":\"CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/centros\\\/sp\\\/riopreto\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/centros\\\/sp\\\/riopreto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centros de pr\u00e1tica\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/centros\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SP\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/centros\\\/sp\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"CEBB S\u00e3o Jos\u00e9 do Rio Preto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/en\/centros\/sp\/riopreto\/","og_locale":"en_GB","og_type":"article","og_title":"CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva","og_description":"Centro urbano de estudos e pr\u00e1ticas em S\u00e3o Jos\u00e9 do Rio Preto, SP Pr\u00e1ticas presenciais | Pr\u00e1ticas online","og_url":"https:\/\/cebb.org.br\/en\/centros\/sp\/riopreto\/","og_site_name":"Centro de Estudos Budistas Bodisatva","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cebb.org.br\/centros\/sp\/riopreto\/","url":"https:\/\/cebb.org.br\/centros\/sp\/riopreto\/","name":"CEBB S\u00e3o Jos\u00e9 do Rio Preto Archives - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"breadcrumb":{"@id":"https:\/\/cebb.org.br\/centros\/sp\/riopreto\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/centros\/sp\/riopreto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Centros de pr\u00e1tica","item":"https:\/\/cebb.org.br\/en\/centros\/"},{"@type":"ListItem","position":3,"name":"SP","item":"https:\/\/cebb.org.br\/en\/centros\/sp\/"},{"@type":"ListItem","position":4,"name":"CEBB S\u00e3o Jos\u00e9 do Rio Preto"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Bodhisattva Center for Buddhist Studies","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Bodhisattva Center for Buddhist Studies","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories\/363"}],"wp:post_type":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts?categories=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}