{"id":103934,"date":"2024-07-25T15:57:59","date_gmt":"2024-07-25T18:57:59","guid":{"rendered":"https:\/\/cebb.org.br\/?p=103934"},"modified":"2024-09-03T07:04:16","modified_gmt":"2024-09-03T10:04:16","slug":"mente-despertar","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/en\/mente-despertar\/","title":{"rendered":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva"},"content":{"rendered":"<p>CEBB Campinas &#8211; 14 de agosto de 2024 \u00e0s 19h30<\/p>\n<p>Presencial e Online<\/p>\n<p><!--more--><\/p>\n<h3><\/h3>\n<h3><strong>SOBRE A PALESTRA<\/strong><\/h3>\n<p><em>\u201cSe n\u00e3o tivermos essa capacidade de olhar para os seres e proteg\u00ea-los, n\u00e3o temos como proteger nem a n\u00f3s mesmos, pois n\u00f3s vivemos totalmente junto com eles&#8221; &#8211; Lama Padma Samten<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Segundo os ensinamentos budistas, o despertar de nossa verdadeira natureza, b\u00fadica e livre de todo sofrimento, passa pelo florescimento da genu\u00edna aspira\u00e7\u00e3o de incluir todos os seres em nosso caminho, de traz\u00ea-los juntos. Como se a ilumina\u00e7\u00e3o n\u00e3o fizesse sentido na perspectiva de uma realiza\u00e7\u00e3o individual.<\/p>\n<p>&nbsp;<\/p>\n<p>Nesta palestra o Lama Padma Samten nos dar\u00e1 ensinamentos preciosos sobre Bodicita, a mente do despertar, a energia sublime que perpassa e impulsiona todo o caminho espiritual, transformando nossas vidas em d\u00e1diva, em oferecimento.<\/p>\n<p>&nbsp;<\/p>\n<p>A vis\u00e3o de mundo, as contempla\u00e7\u00f5es e a pr\u00e1tica, que fazem surgir Bodicita, nos levar\u00e3o a andar pelo mundo com o cora\u00e7\u00e3o aberto e a encontrar cada pessoa, cada ser, com a mesma intimidade e amor que sentimos por nossas m\u00e3es e pais, uma experi\u00eancia profunda de mergulho no sentido \u00faltimo da exist\u00eancia.<\/p>\n<p>&nbsp;<\/p>\n<p>Essa \u00e9 uma palestra recomendada para quem deseja conhecer o caminho espiritual comunicado pelo Buda e n\u00e3o \u00e9 preciso qualquer experi\u00eancia! Esperamos voc\u00eas!<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lama Padma Samten:<\/strong> O mestre budista Lama Padma Samten tem auxiliado in\u00fameras pessoas em suas vidas e rela\u00e7\u00f5es cotidianas, com ensinamentos que dialogam com as mais diversas \u00e1reas do conhecimento. F\u00edsico, com bacharelado e mestrado pela Universidade Federal do Rio Grande do Sul (UFRGS), Alfredo Aveline foi professor de f\u00edsica de 1969 a 1994. Neste per\u00edodo, dedicou-se especialmente ao exame da f\u00edsica qu\u00e2ntica, teoria na qual encontrou afinidade com o pensamento budista. No in\u00edcio dos anos 80, intensificou seu interesse pelo budismo e em 1986 fundou o Centro de Estudos Budistas Bodisatva (CEBB). Em 1993, foi aceito como disc\u00edpulo por Chagdud Tulku Rinpoche e em 1996 foi ordenado lama, t\u00edtulo que significa l\u00edder, sacerdote e professor.<\/p>\n<p>&nbsp;<\/p>\n<h3>Inscri\u00e7\u00e3o e Pr\u00e1tica de Generosidade<\/h3>\n<p>Caso lhe seja poss\u00edvel contribuir, o valor sugerido \u00e9 de R$50,00<\/p>\n<p>&nbsp;<\/p>\n<p>DATA: 14 de agosto de 2024 \u00e1s 19h30<br \/>\nLOCAL: Rua Luiz Vicentin Sobrinho, 135 &#8211; Bar\u00e3o Geraldo (N\u00facleo Cupinzeiro)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Para se inscrever para participa\u00e7\u00e3o PRESENCIAL, <a href=\"https:\/\/forms.gle\/zDgRvXRbGRg65aPr9\">&lt;&lt; clique aqui &gt;&gt;<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Para se inscrever para participa\u00e7\u00e3o ONLINE, <a href=\"https:\/\/acaoparamita.com.br\/ensinamentos\/palestra-a-mente-do-despertar-e-a-vida-como-uma-dadiva\/\">&lt;&lt; clique aqui &gt;&gt;<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Sua contribui\u00e7\u00e3o apoiar\u00e1 as atividades da Escola Caminho do Meio. A pr\u00e1tica da Dana Paramita \u2013 perfei\u00e7\u00e3o da generosidade \u2013 torna poss\u00edvel a continuidade dos ensinamentos desde os tempos do Buda. As seis paramitas \u2013 generosidade, moralidade, paz, energia constante, concentra\u00e7\u00e3o e sabedoria \u2013 inspiram a pr\u00e1tica e s\u00e3o a base geradora e sustentadora dos centros de estudos, medita\u00e7\u00e3o, acolhimento e das iniciativas de educa\u00e7\u00e3o, prote\u00e7\u00e3o ambiental, Terras Puras e Cultura de Paz da Sanga CEBB.<\/p>\n<h3><\/h3>\n<h3>Contact<\/h3>\n<p><a href=\"\/en\/cebbcampinas@gmail.com\/\">cebbcampinas@gmail.com<\/a> |<strong> (19) 98225 0957<\/strong> (WhatsApp)<br \/>\nOrganiza\u00e7\u00e3o: CEBB Campinas e A\u00e7\u00e3o Paramita<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb-org-br.preview-domain.com\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<h4><\/h4>\n<h4>Projects, Practices and Dreams of the \"Middle Way School\" (Escola Caminho do Meio)<\/h4>\n<p>The Middle Way School has welcomed many students over the last 15 years and was delighted to graduate its first 9th grade class in 2022. Operating in a community and a forest, its pedagogical approach is centered on cultivating the inner world, fostering relationships and integrating with nature. It encourages the development of what makes sense to each child, works with play and creativity, art and different languages, and project-based learning - cultivating an education of the mind, heart, hands and whole body. Many dreams have already been realized and many achievements are yet to come. We invite you to be part of this network that believes in Education for Happiness. <strong><a href=\"https:\/\/escolacaminhodomeio.com.br\/apoie\/\">Click here to find out how to get involved.<\/a>.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4>Projects and Dreams of the Bodisatva<\/h4>\n<p>Bodisatva is a communication platform at the service of <i>budismo em solo brasileiro<\/i> and has dedicated its efforts to translating and disseminating wisdom content from authentic lineages in Portuguese, but also to publishing texts produced by masters and practitioners from our own country. The creator of Bodisatva is the first Brazilian to be ordained as a lama in the Nyingma lineage of Tibetan Buddhism, Lama Padma Samten. Based on his vision and confidence that the Buddha's millenary teachings can improve our lives not only individually but collectively, Bodisatva emerged as a vehicle for Buddhism and world transformation: the first magazine of Buddhist thinking in Brazil. <strong><a href=\"https:\/\/bodisatva.com.br\/apoie\/\">Click here to find out how to get involved.<\/a>.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4>Projects and Dreams of Lama Samten<\/h4>\n<p>One of Lama Samten's main aspirations is to support practitioners and retreat centers, especially CEBB Caminho do Meio, CEBB Akanishta and CEBB Jetavana, and to welcome students to the Middle Way School. It's a great gift that there are spaces of silence that make it possible to go deeper into the practice of meditation and that there are also practitioners with this aspiration. <strong><a href=\"https:\/\/cebb-org-br.preview-domain.com\/projetos-e-sonhos-do-lama-samten\/\">Click here to find out how to get involved.<\/a>.<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb-org-br.preview-domain.com\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>CEBB Campinas &#8211; 14 de agosto de 2024 \u00e0s 19h30 Presencial e Online<\/p>","protected":false},"author":39,"featured_media":101255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[365,375,378,647,387,394,399,425,411,412,414,335,341,423,355,363,364],"tags":[692],"class_list":["post-103934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-braganca-paulista","category-campinas","category-cebb-dewachen","category-ilhabela","category-jundiai","category-maresias","category-sao-carlos","category-riopreto","category-sao-jose-dos-campos","category-saopaulo","category-cultura-de-paz","category-eventos-passados","category-marilia","category-pratica-on-line","category-sp","category-treinamento","tag-cebb-campinas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/en\/mente-despertar\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"CEBB Campinas &#8211; 14 de agosto de 2024 \u00e0s 19h30 Presencial e Online\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/en\/mente-despertar\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-25T18:57:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T10:04:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"luisfernando\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"luisfernando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/\"},\"author\":{\"name\":\"luisfernando\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/775e910449c86e423784ae4fa4f5d94b\"},\"headline\":\"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva\",\"datePublished\":\"2024-07-25T18:57:59+00:00\",\"dateModified\":\"2024-09-03T10:04:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/\"},\"wordCount\":882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/52031311042_1780267145_o-1536x1024-1.jpg\",\"keywords\":[\"cebb campinas\"],\"articleSection\":[\"Agenda do Lama Padma Samten\",\"CEBB Bragan\u00e7a Paulista\",\"CEBB Campinas\",\"CEBB Dewachen\",\"CEBB Ilhabela\",\"CEBB Jundia\u00ed\",\"CEBB Maresias\",\"CEBB S\u00e3o Carlos\",\"CEBB S\u00e3o Jos\u00e9 do Rio Preto\",\"CEBB S\u00e3o Jos\u00e9 dos Campos\",\"CEBB S\u00e3o Paulo\",\"Cultura de paz\",\"Eventos Passados\",\"GEBB Mar\u00edlia\",\"Pr\u00e1tica on-line\",\"SP\",\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/\",\"name\":\"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/52031311042_1780267145_o-1536x1024-1.jpg\",\"datePublished\":\"2024-07-25T18:57:59+00:00\",\"dateModified\":\"2024-09-03T10:04:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/52031311042_1780267145_o-1536x1024-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/52031311042_1780267145_o-1536x1024-1.jpg\",\"width\":1536,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mente-despertar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/775e910449c86e423784ae4fa4f5d94b\",\"name\":\"luisfernando\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g\",\"caption\":\"luisfernando\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/author\\\/luisfernando\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/en\/mente-despertar\/","og_locale":"en_GB","og_type":"article","og_title":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva","og_description":"CEBB Campinas &#8211; 14 de agosto de 2024 \u00e0s 19h30 Presencial e Online","og_url":"https:\/\/cebb.org.br\/en\/mente-despertar\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2024-07-25T18:57:59+00:00","article_modified_time":"2024-09-03T10:04:16+00:00","og_image":[{"width":1536,"height":1024,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg","type":"image\/jpeg"}],"author":"luisfernando","twitter_card":"summary_large_image","twitter_misc":{"Written by":"luisfernando","Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/mente-despertar\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/"},"author":{"name":"luisfernando","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/775e910449c86e423784ae4fa4f5d94b"},"headline":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva","datePublished":"2024-07-25T18:57:59+00:00","dateModified":"2024-09-03T10:04:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/"},"wordCount":882,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg","keywords":["cebb campinas"],"articleSection":["Agenda do Lama Padma Samten","CEBB Bragan\u00e7a Paulista","CEBB Campinas","CEBB Dewachen","CEBB Ilhabela","CEBB Jundia\u00ed","CEBB Maresias","CEBB S\u00e3o Carlos","CEBB S\u00e3o Jos\u00e9 do Rio Preto","CEBB S\u00e3o Jos\u00e9 dos Campos","CEBB S\u00e3o Paulo","Cultura de paz","Eventos Passados","GEBB Mar\u00edlia","Pr\u00e1tica on-line","SP","Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/mente-despertar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/mente-despertar\/","url":"https:\/\/cebb.org.br\/mente-despertar\/","name":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg","datePublished":"2024-07-25T18:57:59+00:00","dateModified":"2024-09-03T10:04:16+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/mente-despertar\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/mente-despertar\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/mente-despertar\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2022\/04\/52031311042_1780267145_o-1536x1024-1.jpg","width":1536,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/mente-despertar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Palestra Lama Padma Samten | A Mente do Despertar e a Vida como uma D\u00e1diva"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Bodhisattva Center for Buddhist Studies","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Bodhisattva Center for Buddhist Studies","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/775e910449c86e423784ae4fa4f5d94b","name":"luisfernando","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8441d1af5ef9e03e114889d4476c0f14ac86e0f6e31ab3d76689f9a84ebdb2d1?s=96&d=mm&r=g","caption":"luisfernando"},"url":"https:\/\/cebb.org.br\/en\/author\/luisfernando\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/103934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/users\/39"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/comments?post=103934"}],"version-history":[{"count":11,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/103934\/revisions"}],"predecessor-version":[{"id":104299,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/103934\/revisions\/104299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media\/101255"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media?parent=103934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories?post=103934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/tags?post=103934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}