{"id":53026,"date":"2019-05-03T10:09:31","date_gmt":"2019-05-03T13:09:31","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=53026"},"modified":"2023-06-06T13:32:48","modified_gmt":"2023-06-06T16:32:48","slug":"agenda-cebb-darmata","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/","title":{"rendered":"Agenda do CEBB Darmata"},"content":{"rendered":"<p>Confira a previs\u00e3o de retiros de instru\u00e7\u00f5es do CEBB Darmata e programe-se para participar.<!--more--><br \/>\nAbaixo segue a agenda de retiros do CEBB Darmata. Os retiros de inscri\u00e7\u00f5es e viv\u00eancia s\u00e3o abertos a todos os interessados em conhecer sobre o budismo, medita\u00e7\u00e3o e suas pr\u00e1ticas.<\/p>\n<h3>Agenda 2023<\/h3>\n<p><strong>JUNHO<\/strong><br \/>\n7 a 11 &#8211; Retiro Vida Simples com Monge Koho Mello<\/p>\n<p><strong>JULHO<\/strong><br \/>\n21 a 30 &#8211; Retiro Rio Ganges com Marcelo Nicolodi<\/p>\n<p><strong>AGOSTO<\/strong><br \/>\nViv\u00eancia de medita\u00e7\u00e3o e alimenta\u00e7\u00e3o (data \u00e0 confirmar)<\/p>\n<p><strong>SETEMBRO<\/strong><br \/>\n15 a 17 ou 22 a 24 &#8211; Retiro com Lama Padma Samten (data \u00e0 confirmar)<\/p>\n<p><strong>OUTUBRO<\/strong><br \/>\n11 a 15 &#8211; Viv\u00eancia CEBB Darmata( data \u00e0 confirmar)<\/p>\n<p><strong>NOVEMBRO<\/strong><br \/>\n2 a 5 &#8211; Retiro com Marcia Baja<\/p>\n<p><strong>DEZEMBRO<\/strong><br \/>\n29\/12\/23 \u00e0 01\/01\/24 &#8211; Retiro de Final de Ano.<\/p>\n<h3>Durante todo o ano<\/h3>\n<p><strong>Retiro Aberto, Retiro Fechado<\/strong><br \/>\nSe voc\u00ea j\u00e1 conhece um pouco o Darma e j\u00e1 vem h\u00e1 algum tempo praticando a medita\u00e7\u00e3o, \u00e9 poss\u00edvel passar um tempo vivendo em sanga no CEBB Darmata fora do per\u00edodo de retiros de instru\u00e7\u00f5es. Para mais informa\u00e7\u00f5es <a href=\"https:\/\/cebb.org.br\/en\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/\">clique aqui<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Confira a previs\u00e3o de retiros de instru\u00e7\u00f5es do CEBB Darmata e programe-se para participar.<\/p>","protected":false},"author":4,"featured_media":53047,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[382,336,356,364],"tags":[],"class_list":["post-53026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-darmata","category-cursos-com-tutores","category-retiro-sanga","category-treinamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"Confira a previs\u00e3o de retiros de instru\u00e7\u00f5es do CEBB Darmata e programe-se para participar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-03T13:09:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-06T16:32:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1074\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/\"},\"author\":{\"name\":\"adriana\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\"},\"headline\":\"Agenda do CEBB Darmata\",\"datePublished\":\"2019-05-03T13:09:31+00:00\",\"dateModified\":\"2023-06-06T16:32:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/IMG_20180307_160621604-e1520452839494-1.jpg\",\"articleSection\":[\"CEBB Darmata\",\"Cursos com tutores\",\"Retiro\",\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/\",\"name\":\"Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/IMG_20180307_160621604-e1520452839494-1.jpg\",\"datePublished\":\"2019-05-03T13:09:31+00:00\",\"dateModified\":\"2023-06-06T16:32:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/IMG_20180307_160621604-e1520452839494-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/IMG_20180307_160621604-e1520452839494-1.jpg\",\"width\":1074,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/agenda-cebb-darmata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agenda do CEBB Darmata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\",\"name\":\"adriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"caption\":\"adriana\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/author\\\/adriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/","og_locale":"en_GB","og_type":"article","og_title":"Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva","og_description":"Confira a previs\u00e3o de retiros de instru\u00e7\u00f5es do CEBB Darmata e programe-se para participar.","og_url":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2019-05-03T13:09:31+00:00","article_modified_time":"2023-06-06T16:32:48+00:00","og_image":[{"width":1074,"height":603,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg","type":"image\/jpeg"}],"author":"adriana","twitter_card":"summary_large_image","twitter_misc":{"Written by":"adriana","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/"},"author":{"name":"adriana","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e"},"headline":"Agenda do CEBB Darmata","datePublished":"2019-05-03T13:09:31+00:00","dateModified":"2023-06-06T16:32:48+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/"},"wordCount":173,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg","articleSection":["CEBB Darmata","Cursos com tutores","Retiro","Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/","url":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/","name":"Agenda do CEBB Darmata - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg","datePublished":"2019-05-03T13:09:31+00:00","dateModified":"2023-06-06T16:32:48+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/03\/IMG_20180307_160621604-e1520452839494-1.jpg","width":1074,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/en\/agenda-cebb-darmata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Agenda do CEBB Darmata"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Bodhisattva Center for Buddhist Studies","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Bodhisattva Center for Buddhist Studies","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e","name":"adriana","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","caption":"adriana"},"url":"https:\/\/cebb.org.br\/en\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/53026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/comments?post=53026"}],"version-history":[{"count":6,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/53026\/revisions"}],"predecessor-version":[{"id":97242,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/53026\/revisions\/97242"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media\/53047"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media?parent=53026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories?post=53026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/tags?post=53026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}