{"id":53435,"date":"2018-04-12T10:19:50","date_gmt":"2018-04-12T13:19:50","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=53435"},"modified":"2018-04-12T10:19:50","modified_gmt":"2018-04-12T13:19:50","slug":"palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/en\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/","title":{"rendered":"Palestra e Demonstra\u00e7\u00e3o de Pintura  &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot;"},"content":{"rendered":"<p><strong>5 de junho, ter\u00e7a-feira, \u00e0s 19h30, no teatro da Hebraica<\/strong><br \/>\n<a href=\"https:\/\/cebb.org.br\/en\/kaz-tanahashi-sensei-no-sul\/\" target=\"_blank\" rel=\"noopener\">Veja aqui a Programa\u00e7\u00e3o completa no RS<\/a>.<br \/>\n<!--more--><br \/>\nA cidade de Porto Alegre ter\u00e1 a honra de receber o grande mestre japon\u00eas, erudito e artista <strong>Kazuaki Tahanashi Sensei<\/strong> no m\u00eas de junho para v\u00e1rias atividades: uma exposi\u00e7\u00e3o na UFRGS, palestra no Teatro Hebraica e <a href=\"https:\/\/cebb.org.br\/en\/palestra-e-lancamento-do-livro-sobre-o-sutra-do-coracao-kaz-tanahashi-sensei-porto-alegre\/\">lan\u00e7amento de livro no CEBB PoA<\/a>.<br \/>\nDurante a palestra no Teatro Hebraica, no dia 5 de junho, Kazuaki Tanahashi Sensei tamb\u00e9m far\u00e1 uma demonstra\u00e7\u00e3o de pintura de um &#8220;c\u00edrculo zen&#8221;.<br \/>\nO c\u00edrculo Zen tradicionalmente simboliza &#8220;ilumina\u00e7\u00e3o&#8221; ou &#8220;uma experi\u00eancia plena de cada momento&#8221;. Ele abrange perfeito e imperfeito. O artista e professor Zen, Kazuaki Tanahashi, ir\u00e1 examinar os aspectos hist\u00f3ricos, filos\u00f3ficos e est\u00e9ticos deste s\u00edmbolo enigm\u00e1tico.<br \/>\n<a href=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/2018\/03\/kaz-sensei.jpg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-53801\" title=\"kaz sensei\" src=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/2018\/03\/kaz-sensei-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a>Nascido no Jap\u00e3o em 1933, Kazuaki Tanahashi \u00e9 um erudito e professor Soto Zen. Mestre caligrafista e artista treinado no Jap\u00e3o, h\u00e1 50 anos tem ensinado e feito exposi\u00e7\u00f5es ao redor do mundo. Como escritor, editor e tradutor, produziu mais de quarenta livros em ingl\u00eas e japon\u00eas. Como ativista ambiental, foi o secret\u00e1rio fundador do <em>Plutonium Free Future<\/em>. Ativista da paz, trabalhou contra a corrida armamentista nuclear e nas duas Guerras do Golfo, e \u00e9 diretor fundador da iniciativa <em>A World Without Armies<\/em>, para a desmilitariza\u00e7\u00e3o das na\u00e7\u00f5es. Ele tamb\u00e9m \u00e9 membro da Academia Mundial de Arte e Ci\u00eancia.<br \/>\n<strong>Quando: <\/strong>5 de junho, \u00e0s 19h30<br \/>\n<strong>Place:<\/strong> Teatro Hebraica, Rua General Jo\u00e3o Telles, 508<br \/>\n<strong>Contribui\u00e7\u00e3o sugerida:<\/strong> 50,00<br \/>\nInscri\u00e7\u00e3o no local.<br \/>\nPara conhecer mais sobre o artista, veja o <a href=\"https:\/\/www.youtube.com\/watch?v=fUJR5kJLtF0&amp;index=2&amp;list=PLUJ1bksgoxVMza7lUs1pYTPRIwI_aa-E2&amp;t=0s\" target=\"_blank\" rel=\"noopener\">document\u00e1rio \u201cPainting Peace\u201d (em ingl\u00eas) \u2192<\/a><br \/>\n<strong><a href=\"https:\/\/cebb.org.br\/en\/kaz-tanahashi-sensei-no-rio-grande-do-sul\/\" target=\"_blank\" rel=\"noopener\">Veja aqui a programa\u00e7\u00e3o de atividades de Kazuaki Tanahashi Sensei em Porto Alegre e Viam\u00e3o\/RS<\/a>\u00a0<\/strong><br \/>\n<strong><a href=\"https:\/\/cebb.org.br\/en\/kaz-tanahashi-sensei-no-brasil\/\">E aqui a programa\u00e7\u00e3o em outras regi\u00f5es do pa\u00eds.\u00a0<\/a><\/strong><br \/>\n<a href=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/2018\/04\/Kaz-pincel.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft size-large wp-image-54859\" title=\"Kaz pincel\" src=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/2018\/04\/Kaz-pincel-620x413.jpg\" alt=\"\" width=\"620\" height=\"413\" \/><\/a><br \/>\n<strong>Apoio:<\/strong><br \/>\n<a href=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/1999\/03\/hebraica2.jpeg\"><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-54954\" title=\"hebraica\" src=\"http:\/\/www.cebb.org.br\/wp-content\/uploads\/1999\/03\/hebraica2-150x150.jpeg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>5 de junho, ter\u00e7a-feira, \u00e0s 19h30, no teatro da Hebraica Veja aqui a Programa\u00e7\u00e3o completa no RS.<\/p>","protected":false},"author":122,"featured_media":54958,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[341,364],"tags":[],"class_list":["post-53435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos-passados","category-treinamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/en\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"5 de junho, ter\u00e7a-feira, \u00e0s 19h30, no teatro da Hebraica Veja aqui a Programa\u00e7\u00e3o completa no RS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/en\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T13:19:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot;\",\"datePublished\":\"2018-04-12T13:19:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/\"},\"wordCount\":324,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kazuaki-Tanahashi-2011-Upaya.jpg\",\"articleSection\":[\"Eventos Passados\",\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/\",\"name\":\"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kazuaki-Tanahashi-2011-Upaya.jpg\",\"datePublished\":\"2018-04-12T13:19:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kazuaki-Tanahashi-2011-Upaya.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kazuaki-Tanahashi-2011-Upaya.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/en\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/","og_locale":"en_GB","og_type":"article","og_title":"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva","og_description":"5 de junho, ter\u00e7a-feira, \u00e0s 19h30, no teatro da Hebraica Veja aqui a Programa\u00e7\u00e3o completa no RS.","og_url":"https:\/\/cebb.org.br\/en\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2018-04-12T13:19:50+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/"},"author":{"name":"","@id":""},"headline":"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot;","datePublished":"2018-04-12T13:19:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/"},"wordCount":324,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg","articleSection":["Eventos Passados","Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/","url":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/","name":"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot; - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg","datePublished":"2018-04-12T13:19:50+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/04\/Kazuaki-Tanahashi-2011-Upaya.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/palestra-e-demonstracao-de-pintura-circulo-zen-alem-de-perfeicao-e-imperfeicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Palestra e Demonstra\u00e7\u00e3o de Pintura &quot;C\u00edrculo Zen: al\u00e9m de perfei\u00e7\u00e3o e imperfei\u00e7\u00e3o&quot;"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Bodhisattva Center for Buddhist Studies","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Bodhisattva Center for Buddhist Studies","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"","url":"https:\/\/cebb.org.br\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/53435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/users\/122"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/comments?post=53435"}],"version-history":[{"count":0,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/53435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media\/54958"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media?parent=53435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories?post=53435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/tags?post=53435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}