{"id":65327,"date":"2019-09-22T08:10:49","date_gmt":"2019-09-22T11:10:49","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=65327"},"modified":"2019-09-22T08:10:49","modified_gmt":"2019-09-22T11:10:49","slug":"aw-2019","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/en\/aw-2019\/","title":{"rendered":"Retiro com Lama Alan Wallace 2019"},"content":{"rendered":"<p>De <strong>4 a 11 de Outubro de 2019<\/strong>, retiro com lama Alan Wallace no CEBB Caminho do Meio!<br \/>\n<!--more--><\/em><br \/>\nO CEBB Caminho do Meio tem a alegria de anunciar que o Lama Alan Wallace retorna mais uma vez ao Brasil para compartilhar ensinamentos com a nossa sanga. Sua vinda \u00e9 uma oportunidade rara de aprofundar o estudo e pr\u00e1tica dos ensinamentos do Budismo Tibetano.<br \/>\nNeste retiro, o Lama Alan Wallace oferecer\u00e1 um coment\u00e1rio oral linha-a-linha do <strong>Tantra do Vajra Afiado da Consci\u00eancia L\u00facida<\/strong>, um dos textos vision\u00e1rios mais essenciais e profundos do famoso mestre Dzogchen do s\u00e9culo XIX D\u00fcdjom Lingpa. Esse tantra\u00a0fornece uma exposi\u00e7\u00e3o sobre todo o caminho do Dzogchen, a Grande Perfei\u00e7\u00e3o, transmitido sob a forma de instru\u00e7\u00f5es essenciais e conselhos de cora\u00e7\u00e3o\u00a0nas vis\u00f5es puras de D\u00fcdjom Lingpa.<br \/>\nO <strong>Lama Alan Wallace<\/strong> \u00e9 um dos mais prol\u00edficos autores e tradutores do budismo tibetano no Ocidente. Foi monge budista durante quatorze anos, nas d\u00e9cadas de 70 e 80. Mais tarde, recebeu o t\u00edtulo de Ph.D. pela Universidade de Stanford e atualmente dirige o Instituto Santa Barbara para Estudos da Consci\u00eancia. Autorizado a compartilhar esses ensinamentos por seu Lama Dzogchen, o Vener\u00e1vel Gyatrul Rinpoche, torna essa fonte de sabedoria acess\u00edvel a um p\u00fablico contempor\u00e2neo, com orienta\u00e7\u00e3o passo a passo sobre a teoria e pr\u00e1tica da Grande Perfei\u00e7\u00e3o.<br \/>\nO retiro conta com tradu\u00e7\u00e3o consecutiva para o portugu\u00eas.<\/p>\n<h3>Inscri\u00e7\u00e3o e Detalhes<\/h3>\n<p><strong>N\u00c3O H\u00c1 MAIS VAGAS EM ALOJAMENTOS!<\/strong><br \/>\n<em>Consulte disponibilidade de hospedagem em eventos@cebb.org.br<\/em><br \/>\n<strong>In\u00edcio:<\/strong>\u00a0dia 04\/10, \u00e0s 9h.<br \/>\n<strong>T\u00e9rmino:\u00a0<\/strong>dia 11\/10, \u00e0s 12h.<br \/>\n<strong>Place: <\/strong>Estrada Caminho do Meio, 2600 &#8211; Viam\u00e3o, RS. <a style=\"font-size: 13px;\" href=\"https:\/\/cebb.org.br\/en\/como-chegar-no-cebb-caminho-do-meio\/\">Veja como chegar ao CEBB&#8230;<\/a><br \/>\n<strong>Valor integral:<\/strong> R$ 1.960,00 (inclui ensinamentos, alimenta\u00e7\u00e3o e hospedagem)<br \/>\n<strong>Valor sem hospedagem:<\/strong> R$ 1.640,00<br \/>\n<em>Para garantir a vaga, \u00e9 necess\u00e1rio o pagamento de 30% do valor do evento (R$ 580).\u00a0<strong> Caso o pagamento dos 30% n\u00e3o seja feito ap\u00f3s 1 semana da data da inscri\u00e7\u00e3o, com o envio do comprovante de dep\u00f3sito via email, a inscri\u00e7\u00e3o ser\u00e1 automaticamente cancelada<\/strong>. O restante poder\u00e1 ser pago no dia.<\/em><br \/>\nEm caso de desist\u00eancia, a pol\u00edtica de reembolso \u00e9 a seguinte:<\/p>\n<ul>\n<li><em>At\u00e9 dia 30 de Junho:<\/em> 80% do valor<\/li>\n<li><em>At\u00e9 30 de Julho:<\/em> 50% do valor<\/li>\n<li><em>At\u00e9 30 de Agosto:<\/em> 15% do valor<\/li>\n<li><em>A partir de setembro:<\/em> sem reembolso<\/li>\n<\/ul>\n<h3>Mais informa\u00e7\u00f5es<\/h3>\n<p>Leia com aten\u00e7\u00e3o as\u00a0<a href=\"https:\/\/cebb.org.br\/en\/orientacoes-para-os-visitantes-do-cebb-caminho-do-meio\/\">orienta\u00e7\u00f5es gerais aos visitantes do CEBB<\/a>.<br \/>\n<strong>Refei\u00e7\u00f5es<\/strong><br \/>\nAs refei\u00e7\u00f5es durante o retiro s\u00e3o simples e seguem a linha vegetariana. Nosso card\u00e1pio \u00e9 feito por uma nutricionista que os elabora de forma saud\u00e1vel e equilibrada. N\u00e3o consumimos caf\u00e9, nem a\u00e7\u00facar branco e o consumo de latic\u00ednios \u00e9 reduzido.<br \/>\n<strong>Hospedagem<\/strong><br \/>\n<strong><\/strong> A hospedagem \u00e9 em alojamentos coletivos. Tamb\u00e9m \u00e9 poss\u00edvel alugar quartos na casa de moradores, se voc\u00ea escolher essa op\u00e7\u00e3o, escreva para n\u00f3s para que possamos lhe passar o contato dos moradores que alugam quartos. A combina\u00e7\u00e3o \u00e9 feita diretamente entre o interessado e o morador.<br \/>\n<strong>Importante: sua inscri\u00e7\u00e3o deve ser feita apenas ap\u00f3s a combina\u00e7\u00e3o com o morador!<\/strong><br \/>\n<strong><\/strong><strong>IMPORTANTE:<\/strong>\u00a0Trazer travesseiro, cobertor, roupa de cama e banho, guarda-chuva, lanterna.<br \/>\n<strong>Atividades volunt\u00e1rias<\/strong><br \/>\n<strong><\/strong>Os participantes dos eventos no CEBB s\u00e3o convidados a praticarem desenvolvendo atividades de limpeza e organiza\u00e7\u00e3o. As atividades volunt\u00e1rias para manuten\u00e7\u00e3o dos espa\u00e7os durante os eventos fazem parte do treinamento da mente e da energia e contribuem para a realiza\u00e7\u00e3o dos eventos de forma participativa e coletiva.<\/p>\n<h3>Contact<\/h3>\n<p>eventos@cebb.org.br, (51) 98051 5255\u00a0| Hor\u00e1rio de atendimento: de segunda \u00e0 sexta, das 13h \u00e0s 18h.<\/p>","protected":false},"excerpt":{"rendered":"<p>De 4 a 11 de Outubro de 2019, retiro com lama Alan Wallace no CEBB Caminho do Meio!<\/p>","protected":false},"author":128,"featured_media":65151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[339,341],"tags":[],"class_list":["post-65327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ensinamentos-mestres","category-eventos-passados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retiro com Lama Alan Wallace 2019 Budismo<\/title>\n<meta name=\"description\" content=\"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre &quot;O Tantra do Vajra Afiado&quot; de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/en\/aw-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiro com Lama Alan Wallace 2019 Budismo\" \/>\n<meta property=\"og:description\" content=\"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre &quot;O Tantra do Vajra Afiado&quot; de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/en\/aw-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-22T11:10:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1379\" \/>\n\t<meta property=\"og:image:height\" content=\"498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Retiro com Lama Alan Wallace 2019\",\"datePublished\":\"2019-09-22T11:10:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/\"},\"wordCount\":605,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Schermata-2017-04-28-alle-18.20.35.png\",\"articleSection\":[\"Ensinamentos de grandes mestres\",\"Eventos Passados\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/\",\"name\":\"Retiro com Lama Alan Wallace 2019 Budismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Schermata-2017-04-28-alle-18.20.35.png\",\"datePublished\":\"2019-09-22T11:10:49+00:00\",\"description\":\"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre \\\"O Tantra do Vajra Afiado\\\" de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Schermata-2017-04-28-alle-18.20.35.png\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/Schermata-2017-04-28-alle-18.20.35.png\",\"width\":1379,\"height\":498},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/aw-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiro com Lama Alan Wallace 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiro com Lama Alan Wallace 2019 Budismo","description":"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre \"O Tantra do Vajra Afiado\" de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/en\/aw-2019\/","og_locale":"en_GB","og_type":"article","og_title":"Retiro com Lama Alan Wallace 2019 Budismo","og_description":"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre \"O Tantra do Vajra Afiado\" de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.","og_url":"https:\/\/cebb.org.br\/en\/aw-2019\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2019-09-22T11:10:49+00:00","og_image":[{"width":1379,"height":498,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Estimated reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/"},"author":{"name":"","@id":""},"headline":"Retiro com Lama Alan Wallace 2019","datePublished":"2019-09-22T11:10:49+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/"},"wordCount":605,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png","articleSection":["Ensinamentos de grandes mestres","Eventos Passados"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/en\/aw-2019\/","url":"https:\/\/cebb.org.br\/en\/aw-2019\/","name":"Retiro com Lama Alan Wallace 2019 Budismo","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png","datePublished":"2019-09-22T11:10:49+00:00","description":"De 4 a 11 de Outubro 2019, retiro com lama Alan Wallace, sobre \"O Tantra do Vajra Afiado\" de D\u00fcdjom Lingpa, no CEBB Caminho do Meio.","breadcrumb":{"@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/en\/aw-2019\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2017\/05\/Schermata-2017-04-28-alle-18.20.35.png","width":1379,"height":498},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/en\/aw-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Retiro com Lama Alan Wallace 2019"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Bodhisattva Center for Buddhist Studies","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Bodhisattva Center for Buddhist Studies","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"","url":"https:\/\/cebb.org.br\/en\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/65327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/comments?post=65327"}],"version-history":[{"count":0,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/posts\/65327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media\/65151"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/media?parent=65327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/categories?post=65327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/en\/wp-json\/wp\/v2\/tags?post=65327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}