{"id":333,"count":11,"description":"","link":"https:\/\/cebb.org.br\/es\/category\/sanga\/108-horas\/","name":"108 horas","slug":"108-horas","taxonomy":"category","parent":332,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>108 horas Archives - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/es\/sanga\/108-horas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"108 horas Archives - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/es\/sanga\/108-horas\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sanga\\\/108-horas\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/sanga\\\/108-horas\\\/\",\"name\":\"108 horas Archives - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sanga\\\/108-horas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sanga\\\/108-horas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\".Tipo de atividade\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/sanga\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"108 horas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"108 horas Archives - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/es\/sanga\/108-horas\/","og_locale":"es_ES","og_type":"article","og_title":"108 horas Archives - Centro de Estudos Budistas Bodisatva","og_url":"https:\/\/cebb.org.br\/es\/sanga\/108-horas\/","og_site_name":"Centro de Estudos Budistas Bodisatva","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cebb.org.br\/sanga\/108-horas\/","url":"https:\/\/cebb.org.br\/sanga\/108-horas\/","name":"108 horas Archives - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"breadcrumb":{"@id":"https:\/\/cebb.org.br\/sanga\/108-horas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/sanga\/108-horas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":".Tipo de atividade","item":"https:\/\/cebb.org.br\/en\/sanga\/"},{"@type":"ListItem","position":3,"name":"108 horas"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centro de Estudios Budistas Bodisatva","description":"Budismo, meditaci\u00f3n y cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centro de Estudios Budistas Bodisatva","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories\/333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories\/332"}],"wp:post_type":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts?categories=333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}