{"id":16773,"date":"2022-11-21T11:50:22","date_gmt":"2022-11-21T14:50:22","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=16773"},"modified":"2022-11-21T16:18:16","modified_gmt":"2022-11-21T19:18:16","slug":"praticas-regulares-co","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/es\/praticas-regulares-co\/","title":{"rendered":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed"},"content":{"rendered":"<p>Ol\u00e1! Seja bem-vind@! Aqui voc\u00ea encontra nossa programa\u00e7\u00e3o de pr\u00e1ticas, orienta\u00e7\u00f5es sobre as atividades e dicas para os iniciantes.<br \/>\n<!--more--><br \/>\nSob orienta\u00e7\u00e3o do <strong>Lama Padma Samten<\/strong>, oferecemos pr\u00e1ticas e estudos em v\u00e1rios dias da semana.<\/p>\n<p>Confira abaixo nossa programa\u00e7\u00e3o online, partilhada pelos CEBBs Bras\u00edlia, Alto Para\u00edso e Goi\u00e2nia e pelos GEBBs Taguatinga\/DF e GEBB Jata\u00ed\/GO.<\/p>\n<p><strong>Segundas<\/strong><br \/>\n19h15 \u00e0s 20h45 | Introdu\u00e7\u00e3o ao Budismo e ao CEBB<br \/>\n<strong>Ter\u00e7as<\/strong><br \/>\n17h30 \u00e0s 18h30 | Medita\u00e7\u00e3o (conduzida)<br \/>\n18h30 \u00e0s 19h00 | Medita\u00e7\u00e3o (silenciosa)<br \/>\n<strong>Quartas<\/strong><br \/>\n17h00 \u00e0s 18h00 | Estudo do retiro &#8220;Meditando a Vida&#8221;, de Lama Padma Samten<br \/>\n<strong>Quintas<\/strong><br \/>\n08h00 \u00e0s 09h00 | Medita\u00e7\u00e3o (conduzida)<br \/>\n09h00 \u00e0s 10h00 | Estudo do livro &#8220;Quando tudo se desfaz&#8221;, de Pema Ch\u00f6dron<br \/>\n<strong>Sextas<\/strong><br \/>\n18h00 \u00e0s 19h00 | Estudo do livro &#8220;Mandala do L\u00f3tus&#8221;, de Lama Padma Samten<\/p>\n<p><strong>Para entrar na nossa sala online, <a href=\"https:\/\/us04web.zoom.us\/j\/3978474038\">clique aqui<\/a>.<\/strong> A senha \u00e9: buda. A sala \u00e9 aberta minutos antes de cada pr\u00e1tica. Utilizamos a plataforma <a href=\"https:\/\/zoom.us\/download\">Zoom<\/a>, que pode ser instalada em celulares, tablets e computadores.<\/p>\n<h4>Sobre as nossas pr\u00e1ticas<\/h4>\n<p>Apresentamos abaixo perguntas e respostas sobre como acontecem as nossas pr\u00e1ticas e uma breve explica\u00e7\u00e3o de cada uma delas.<\/p>\n<p><strong>Qualquer pessoa pode participar das pr\u00e1ticas?<\/strong><br \/>\nSim! Nossas pr\u00e1ticas n\u00e3o t\u00eam pr\u00e9-requisitos. Nelas, pessoas de variadas idades, sejam iniciantes ou praticantes experientes, partilham, em roda, dos estudos, contempla\u00e7\u00f5es e medita\u00e7\u00f5es. Para participar, basta chegar!<\/p>\n<p><strong>Como elas funcionam? S\u00e3o um curso (com in\u00edcio, meio e fim)? Tenho que esperar abrir uma nova turma?<\/strong><br \/>\nO CEBB \u00e9 &#8220;uma escola aberta para alunos livres&#8221;: um espa\u00e7o privilegiado de estudo de ensinamentos que revelam a origem das dificuldades que todos os seres enfrentam e como super\u00e1-las, sem que, para isto, as pessoas precisem fazer uma confiss\u00e3o de f\u00e9 budista. Dessa forma, nossas pr\u00e1ticas regulares n\u00e3o s\u00e3o exatamente um curso. Funcionam assim: a cada encontro \u00e9 feita a leitura e contempla\u00e7\u00e3o de um ensinamento (em texto, v\u00eddeo, etc.), dentro do tema da pr\u00e1tica espec\u00edfica. Um facilitador &#8211; praticante com um pouco mais de experi\u00eancia &#8211; exp\u00f5e o ensinamento e, coletivamente, vamos descortinando seus aspectos essenciais. As perguntas s\u00e3o sempre bem-vindas. Como o m\u00e9todo do CEBB \u00e9 circular, vamos rever muitas vezes, sob variados pontos de vista, o mesmo ensinamento. Assim, mesmo em estudos longos, a qualquer momento \u00e9 poss\u00edvel se juntar ao grupo, pois cada encontro guarda sua riqueza.<\/p>\n<p><strong>Posso entrar na pr\u00e1tica sem ter chegado no hor\u00e1rio? Posso sair antes?<\/strong><br \/>\nSim! Se a pr\u00e1tica n\u00e3o come\u00e7ou, junte-se a n\u00f3s para um ch\u00e1 e aproveite para visitar a nossa lojinha e biblioteca. Se a pr\u00e1tica j\u00e1 tiver come\u00e7ado, basta entrar, tirar os cal\u00e7ados e, em sil\u00eancio, se juntar ao grupo na pr\u00e1tica. E caso deseje se ausentar antes do t\u00e9rmino, sem problemas tamb\u00e9m. E no caso das pr\u00e1ticas online, tamb\u00e9m pode entrar e sair quando necessitar.<\/p>\n<p><strong>De que trata cada pr\u00e1tica?<\/strong><\/p>\n<p><em>Introdu\u00e7\u00e3o ao Budismo e ao CEBB<\/em><br \/>\nNesta pr\u00e1tica, acolhemos as pessoas que est\u00e3o chegando e contemplamos juntos, de forma c\u00edclica, temas introdut\u00f3rios, tais como:<br \/>\n&#8211; Hist\u00f3ria do pr\u00edncipe Sidarta Gautama, que se torna o Buda Shakyamuni;<br \/>\n&#8211; As diferentes linhagens do Budismo, com enf\u00e2se no Budismo Tibetano e no CEBB;<br \/>\n&#8211; As preces feitas no in\u00edcio das pr\u00e1ticas;<br \/>\n&#8211; Aspectos fundamentais do Budismo: As 4 Nobres Verdades, Os 4 Pensamentos Que Transformam a Mente e As 6 Paramitas (Perfei\u00e7\u00f5es);<br \/>\n&#8211; Introdu\u00e7\u00e3o ao Roteiro de 21 Itens (roteiro de treinamento oferecido pelo Lama Padma Samten);<br \/>\n&#8211; Introdu\u00e7\u00e3o \u00e0 Medita\u00e7\u00e3o do Calmo Repousar (shamata);<br \/>\n&#8211; Introdu\u00e7\u00e3o \u00e0 Medita\u00e7\u00e3o da Bondade Amorosa (Metabavana).<\/p>\n<p><em>Medita\u00e7\u00e3o Conduzida e Medita\u00e7\u00e3o Silenciosa<\/em><br \/>\nNesta pr\u00e1tica, experienciamos a medita\u00e7\u00e3o silenciosa (conduzida ou n\u00e3o), com base no roteiro de pr\u00e1ticas do Lama Padma Samten.<\/p>\n<p><em>&#8220;A medita\u00e7\u00e3o sempre implica na observa\u00e7\u00e3o e disciplina de tr\u00eas aspectos &#8211; corpo, fala e mente. A primeira \u00e2ncora \u00e9 o corpo. Apenas sentando im\u00f3veis j\u00e1 estamos removendo obst\u00e1culos que se interp\u00f5em \u00e0 a\u00e7\u00e3o de imobilidade. (\u2026) Ao ficarmos im\u00f3veis, estamos disciplinando a mente atrav\u00e9s do corpo. A segunda \u00e2ncora \u00e9 a fala, que inclui a respira\u00e7\u00e3o e tamb\u00e9m as energias internas do corpo. Fala significa respira\u00e7\u00e3o serena, inspirar e expirar serena e silenciosamente. O terceiro aspecto \u00e9 a mente, que foca a respira\u00e7\u00e3o e a experi\u00eancia de serenidade. (\u2026) \u00c9 a pr\u00e1tica do repousar tranquilo.\u201d (Lama Padma Samten)<\/em><\/p>\n<h4>Generosidade<\/h4>\n<p>O Darma se sustenta e expande atrav\u00e9s de doa\u00e7\u00f5es desde os tempos do Buda, que mendigava aonde quer que fosse. Da mesma forma, todas as a\u00e7\u00f5es do CEBB s\u00e3o mantidas pela generosidade da comunidade.<\/p>\n<p>As contribui\u00e7\u00f5es espont\u00e2neas e com alegria no cora\u00e7\u00e3o mant\u00e9m o local e as pr\u00e1ticas, permitindo aos visitantes e praticantes ouvir os ensinamentos, pratic\u00e1-los e transformar suas vidas.<\/p>\n<p>Convidamos tod@s a serem generosos, mas sempre ressaltamos que &#8220;ningu\u00e9m fica de fora&#8221; \u2013 t@dos sempre ser\u00e3o bem vind@s para participar das pr\u00e1ticas e estudos, independente de doa\u00e7\u00f5es.<\/p>\n<p>Para realizar uma doa\u00e7\u00e3o, coloque diretamente nas nossas caixinhas, fale com qualquer facilitador durante as pr\u00e1ticas ou entre em contato via brasilia@cebb.org.br (que tamb\u00e9m \u00e9 nosso pix).<\/p>\n<p>H\u00e1 tamb\u00e9m outras formas de oferecimento: acolher as pessoas que chegam, zelar pelo espa\u00e7o, trazer lanchinhos, doar roupas usadas para o brech\u00f3, adquirir itens na nossa lojinha, etc.<\/p>\n<p>Que os m\u00e9ritos se expandam!<\/p>\n<h4>Informativo por e-mail<\/h4>\n<p>Para ser avisado de palestras, cursos, retiros e atividades especiais, <a href=\"http:\/\/eepurl.com\/OsCOP\" target=\"_blank\" rel=\"noopener\">cadastre-se<\/a> para receber nosso informativo.<\/p>\n<h4>P\u00e1ginas e contatos<\/h4>\n<p>E-mail: <a href=\"mailto:brasilia@cebb.org.br\">brasilia@cebb.org.br<\/a><br \/>\nContatos via WhatsApp: 61-99996-0910 (Camila), 61-99881-9976 (Gabriel).<br \/>\nInstagram: <a href=\"http:\/\/www.instagram.com\/cebb_brasilia\/\">@cebb_brasilia<\/a><br \/>\nFacebook: <a href=\"http:\/\/www.facebook.com\/cebb.brasilia\/\">@cebb.brasilia<\/a><\/p>\n<p><script type=\"text\/javascript\" src=\"moz-extension:\/\/8c9a78ae-50a6-4840-92fd-bb471cffcc5c\/js\/app.js\"><\/script><\/p>","protected":false},"excerpt":{"rendered":"<p>Ol\u00e1! Seja bem-vind@! Aqui voc\u00ea encontra nossa programa\u00e7\u00e3o de pr\u00e1ticas, orienta\u00e7\u00f5es sobre as atividades e dicas para os iniciantes.<\/p>","protected":false},"author":4,"featured_media":10002,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[371,376,386,354],"tags":[],"class_list":["post-16773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alto-paraiso","category-brasilia","category-cebb-goiania","category-pratica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/es\/praticas-regulares-co\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"Ol\u00e1! Seja bem-vind@! Aqui voc\u00ea encontra nossa programa\u00e7\u00e3o de pr\u00e1ticas, orienta\u00e7\u00f5es sobre as atividades e dicas para os iniciantes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/es\/praticas-regulares-co\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T14:50:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T19:18:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"adriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/\"},\"author\":{\"name\":\"adriana\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\"},\"headline\":\"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed\",\"datePublished\":\"2022-11-21T14:50:22+00:00\",\"dateModified\":\"2022-11-21T19:18:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/\"},\"wordCount\":1002,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/VELAS-e1395422055758.jpg\",\"articleSection\":[\"CEBB Alto Para\u00edso\",\"CEBB Bras\u00edlia\",\"CEBB Goi\u00e2nia\",\"Pr\u00e1tica\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/\",\"name\":\"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/VELAS-e1395422055758.jpg\",\"datePublished\":\"2022-11-21T14:50:22+00:00\",\"dateModified\":\"2022-11-21T19:18:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/VELAS-e1395422055758.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/VELAS-e1395422055758.jpg\",\"width\":600,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/praticas-regulares-co\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\",\"name\":\"adriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"caption\":\"adriana\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/es\\\/author\\\/adriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/es\/praticas-regulares-co\/","og_locale":"es_ES","og_type":"article","og_title":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva","og_description":"Ol\u00e1! Seja bem-vind@! Aqui voc\u00ea encontra nossa programa\u00e7\u00e3o de pr\u00e1ticas, orienta\u00e7\u00f5es sobre as atividades e dicas para os iniciantes.","og_url":"https:\/\/cebb.org.br\/es\/praticas-regulares-co\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2022-11-21T14:50:22+00:00","article_modified_time":"2022-11-21T19:18:16+00:00","og_image":[{"width":600,"height":450,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg","type":"image\/jpeg"}],"author":"adriana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adriana","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/"},"author":{"name":"adriana","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e"},"headline":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed","datePublished":"2022-11-21T14:50:22+00:00","dateModified":"2022-11-21T19:18:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/"},"wordCount":1002,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg","articleSection":["CEBB Alto Para\u00edso","CEBB Bras\u00edlia","CEBB Goi\u00e2nia","Pr\u00e1tica"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/","url":"https:\/\/cebb.org.br\/praticas-regulares-co\/","name":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg","datePublished":"2022-11-21T14:50:22+00:00","dateModified":"2022-11-21T19:18:16+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/praticas-regulares-co\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2014\/03\/VELAS-e1395422055758.jpg","width":600,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/praticas-regulares-co\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e1ticas Regulares | CEBB Bras\u00edlia, CEBB Alto Para\u00edso, CEBB Goi\u00e2nia, GEBB Taguatinga, GEBB Jata\u00ed"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centro de Estudios Budistas Bodisatva","description":"Budismo, meditaci\u00f3n y cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centro de Estudios Budistas Bodisatva","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e","name":"adriana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","caption":"adriana"},"url":"https:\/\/cebb.org.br\/es\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/16773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/comments?post=16773"}],"version-history":[{"count":7,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/16773\/revisions"}],"predecessor-version":[{"id":93064,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/16773\/revisions\/93064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/media\/10002"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/media?parent=16773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories?post=16773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/tags?post=16773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}