{"id":52986,"date":"1998-03-07T12:56:26","date_gmt":"1998-03-07T15:56:26","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=52986"},"modified":"2026-05-06T12:06:19","modified_gmt":"2026-05-06T15:06:19","slug":"retiro-aberto-darmata","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/es\/retiro-aberto-darmata\/","title":{"rendered":"Retiros Abertos no CEBB Darmata"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>CEBB Darmata<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O CEBB Darmata surge da aspira\u00e7\u00e3o do Lama Padma Samten de estabelecer um centro de Darma voltado especialmente para a pr\u00e1tica de retiros curtos e longos. Primeiro CEBB rural fundado fora do Rio Grande do Sul, o Darmata tamb\u00e9m desponta como oportunidade para praticantes do Norte e Nordeste do Brasil praticarem o Darma e terem a chance de participar da estrutura\u00e7\u00e3o de um espa\u00e7o de trabalho e moradia a partir da pr\u00e1tica dos ensinamentos budistas.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Retiro Aberto<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O Retiro Aberto \u00e9 dedicado ao aprofundamento da pr\u00e1tica de medita\u00e7\u00e3o, do estudo dos ensinamentos e o treinamento da vis\u00e3o, com acompanhamento individual realizado por tutores do Programa de Forma\u00e7\u00e3o de Facilitadores do CEBB.<\/p>\n<p>As atividades di\u00e1rias incluem estudos de textos budistas, pr\u00e1tica de medita\u00e7\u00e3o e realiza\u00e7\u00e3o de pujas.<\/p>\n<p>Nesta modalidade de retiro, o praticante pode dedicar a maior parte do seu tempo \u00e0 pr\u00e1tica formal. Mas pode tamb\u00e9m oferecer algumas horas do dia para a pr\u00e1tica do SAMU (trabalho volunt\u00e1rio).<\/p>\n<p>Durante o per\u00edodo do retiro, o praticante ter\u00e1 a oportunidade de participar das pr\u00e1ticas di\u00e1rias e da rotina de atividades gerais junto \u00e0 comunidade de moradores.<br \/>\nOs participantes do retiro aberto receber\u00e3o refei\u00e7\u00f5es vegetarianas, acomoda\u00e7\u00f5es em alojamentos coletivos, e acompanhamento com um tutor local, podendo participar das pr\u00e1ticas de medita\u00e7\u00e3o, estudos, pr\u00e1ticas de corpo e pujas e a chance de experimentar a vida em um centro de Darma.<\/p>\n<p>O CEBB n\u00e3o possui funcion\u00e1rios e, portanto, a manuten\u00e7\u00e3o e limpeza do lugar \u00e9 feita por n\u00f3s, que moramos ou frequentamos o espa\u00e7o. Todos est\u00e3o convidados a tomar a harmoniza\u00e7\u00e3o e o cuidado com o espa\u00e7o como uma pr\u00e1tica de aten\u00e7\u00e3o e respeito ao pr\u00f3prio Darma. A harmonia dos nossos movimentos em comunidade \u00e9 um reflexo direto das qualidades da nossa pr\u00f3pria pr\u00e1tica. A rotina de atividades pode ser combinada com os coordenadores e\/ou os tutores residentes na chegada do praticante ao CEBB.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sustenta\u00e7\u00e3o<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>O CEBB Darmata se sustenta a partir da generosidade e do engajamento da pr\u00f3pria sanga (comunidade de praticantes). Atrav\u00e9s das doa\u00e7\u00f5es e das contribui\u00e7\u00f5es nos eventos \u00e9 poss\u00edvel manter a estrutura do Darmata viva. \u00c9 recomenda\u00e7\u00e3o clara do Lama que ningu\u00e9m deixe de ouvir o Darma por motivos financeiros, mas \u00e9 importante contemplar que nossa contribui\u00e7\u00e3o favorece n\u00e3o apenas a cobertura de gastos, mas a sustenta\u00e7\u00e3o e expans\u00e3o do Darma agora e em tempos futuros. As contribui\u00e7\u00f5es sugeridas para retiros abertos est\u00e3o descritas no nosso formul\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Rotina Di\u00e1ria do CEBB Darmata<\/strong><\/h3>\n<p>5h30 \u2013 6h Medita\u00e7\u00e3o silenciosa<br \/>\n6h \u2013 7h Puja<br \/>\n7h \u2013 7h45 Caf\u00e9 da manh\u00e3<br \/>\n8h \u2013 9h Mandala de Trabalho ou Hor\u00e1rio livre<br \/>\n9h \u2013 11h Mandala de Trabalho ou Medita\u00e7\u00e3o silenciosa<br \/>\n11h \u2013 12h Mandala de Trabalho ou Hor\u00e1rio livre<br \/>\n12h \u2013 12h45 Almo\u00e7o<br \/>\n13h \u2013 15h Hor\u00e1rio livre<br \/>\n15h \u2013 17h Medita\u00e7\u00e3o silenciosa<br \/>\n17h \u2013 18h Atividade f\u00edsica<br \/>\n18h \u2013 18h45 Jantar<br \/>\n19h \u2013 20h Puja<br \/>\n20h \u2013 22h Hor\u00e1rio livre ou Atividade especial<br \/>\n22h Nobre sil\u00eancio e Recolhimento<\/p>\n<p>&nbsp;<\/p>\n<p>A frequ\u00eancia e o hor\u00e1rio dos estudos e das pr\u00e1ticas de corpo s\u00e3o combinados com os moradoradores e praticantes em retiro e podem variar de acordo com a disponibilidades dos facilitadores de cada atividade.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Solicita\u00e7\u00e3o de inscri\u00e7\u00e3o<\/strong><\/h3>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li>Se voc\u00ea \u00e9 novo no CEBB, primeiro conhe\u00e7a mais sobre o budismo tibetano nos nossos centros urbanos ou online (<a href=\"https:\/\/cebb.org.br\/es\/centros-no-brasil\/\" target=\"_blank\" rel=\"noopener\">verifique se existe algum CEBB perto de voc\u00ea<\/a>) e no youtube do CEBB e do Lama Padma Samten. Alguns bons livros para come\u00e7ar s\u00e3o: Meditando a Vida, A J\u00f3ia dos Desejos, A Roda da Vida e Mandala do L\u00f3tus, todos de autoria do Lama Padma Samten.<\/li>\n<li>Preencha o Formul\u00e1rio de Solicita\u00e7\u00e3o de Inscri\u00e7\u00e3o.<\/li>\n<li>Os pedidos ser\u00e3o analisados e o contato ter\u00e1 continuidade por e-mail ou algum outro meio de comunica\u00e7\u00e3o.<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p><a style=\"display: inline-block; background-color: #b8190d; color: #ffffff; font-size: 14px; font-weight: bold; padding: 3px 18px 10px 18px; text-align: center; border-radius: 15px; text-decoration: none; transition: background 0.3s ease-in-out; line-height: 1;\" href=\"https:\/\/forms.gle\/mSTAzkWB91waKMCr5\" target=\"_blank\" rel=\"noopener\"><br \/>\nClique para abrir o Formul\u00e1rio de Inscri\u00e7\u00e3o<br \/>\n<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Local<\/strong><\/h3>\n<p><strong>CEBB Darmata<\/strong>, Fazenda Nossa Senhora, Zona Rural de Timba\u00faba-PE.<\/p>\n<p><iframe style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3956.0938287868953!2d-35.3118207!3d-7.454871499999999!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x7ac79505b7a9249%3A0x343b724dcefa2852!2sCEBB+Darmata!5e0!3m2!1spt-BR!2sbr!4v1439314261298\" width=\"400\" height=\"300\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/p>\n<p>Mais informa\u00e7\u00f5es de como chegar na p\u00e1gina <a href=\"https:\/\/cebb.org.br\/es\/como-chegar-ao-darmata\/\">http:\/\/www.cebb.org.br\/como-chegar-ao-darmata\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Contato<\/strong><\/h3>\n<p>Whatsapp: (81) 99229.2904 | Email: retiros.cebbdarmata@gmail.com<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; CEBB Darmata &nbsp; O CEBB Darmata surge da aspira\u00e7\u00e3o do Lama Padma Samten de estabelecer um centro de Darma voltado especialmente para a pr\u00e1tica de retiros curtos e longos. Primeiro CEBB rural fundado fora do Rio Grande do Sul, o Darmata tamb\u00e9m desponta como oportunidade para praticantes do Norte e Nordeste do Brasil praticarem [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[364],"tags":[],"class_list":["post-52986","post","type-post","status-publish","format-standard","hentry","category-treinamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/es\/retiro-aberto-darmata\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"&nbsp; CEBB Darmata &nbsp; O CEBB Darmata surge da aspira\u00e7\u00e3o do Lama Padma Samten de estabelecer um centro de Darma voltado especialmente para a pr\u00e1tica de retiros curtos e longos. Primeiro CEBB rural fundado fora do Rio Grande do Sul, o Darmata tamb\u00e9m desponta como oportunidade para praticantes do Norte e Nordeste do Brasil praticarem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/es\/retiro-aberto-darmata\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"1998-03-07T15:56:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T15:06:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" \/>\n\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t<meta property=\"og:image:height\" content=\"23\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"adriana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"adriana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/\"},\"author\":{\"name\":\"adriana\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\"},\"headline\":\"Retiros Abertos no CEBB Darmata\",\"datePublished\":\"1998-03-07T15:56:26+00:00\",\"dateModified\":\"2026-05-06T15:06:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/\"},\"wordCount\":734,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linha-com-no-infinto.png\",\"articleSection\":[\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/\",\"name\":\"Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linha-com-no-infinto.png\",\"datePublished\":\"1998-03-07T15:56:26+00:00\",\"dateModified\":\"2026-05-06T15:06:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linha-com-no-infinto.png\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/linha-com-no-infinto.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-darmata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiros Abertos no CEBB Darmata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2943f7434cfdce8a50054bcca9da418e\",\"name\":\"adriana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g\",\"caption\":\"adriana\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/es\\\/author\\\/adriana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/es\/retiro-aberto-darmata\/","og_locale":"es_ES","og_type":"article","og_title":"Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva","og_description":"&nbsp; CEBB Darmata &nbsp; O CEBB Darmata surge da aspira\u00e7\u00e3o do Lama Padma Samten de estabelecer um centro de Darma voltado especialmente para a pr\u00e1tica de retiros curtos e longos. Primeiro CEBB rural fundado fora do Rio Grande do Sul, o Darmata tamb\u00e9m desponta como oportunidade para praticantes do Norte e Nordeste do Brasil praticarem [&hellip;]","og_url":"https:\/\/cebb.org.br\/es\/retiro-aberto-darmata\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"1998-03-07T15:56:26+00:00","article_modified_time":"2026-05-06T15:06:19+00:00","og_image":[{"width":150,"height":23,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png","type":"image\/png"}],"author":"adriana","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"adriana","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/"},"author":{"name":"adriana","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e"},"headline":"Retiros Abertos no CEBB Darmata","datePublished":"1998-03-07T15:56:26+00:00","dateModified":"2026-05-06T15:06:19+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/"},"wordCount":734,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png","articleSection":["Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/","url":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/","name":"Retiros Abertos no CEBB Darmata - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png","datePublished":"1998-03-07T15:56:26+00:00","dateModified":"2026-05-06T15:06:19+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/retiro-aberto-darmata\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/retiro-aberto-darmata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Retiros Abertos no CEBB Darmata"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centro de Estudios Budistas Bodisatva","description":"Budismo, meditaci\u00f3n y cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centro de Estudios Budistas Bodisatva","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2943f7434cfdce8a50054bcca9da418e","name":"adriana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f235a6769909b7357e271e7b95d7f24ff1268d2236b0a381c02f83a6368721f1?s=96&d=mm&r=g","caption":"adriana"},"url":"https:\/\/cebb.org.br\/es\/author\/adriana\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/52986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/comments?post=52986"}],"version-history":[{"count":36,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/52986\/revisions"}],"predecessor-version":[{"id":121926,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/52986\/revisions\/121926"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/media?parent=52986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories?post=52986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/tags?post=52986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}