{"id":99250,"date":"2024-01-26T16:00:18","date_gmt":"2024-01-26T19:00:18","guid":{"rendered":"https:\/\/cebb.org.br\/?p=99250"},"modified":"2024-02-09T07:11:50","modified_gmt":"2024-02-09T10:11:50","slug":"lama-samten-em-alto-paraiso","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/es\/lama-samten-em-alto-paraiso\/","title":{"rendered":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso"},"content":{"rendered":"<p>O per\u00edodo completo dos retiros ser\u00e1 de 23 a 04 de fevereiro. Voc\u00ea poder\u00e1 fazer o retiro completo ou em partes, confira!<br \/>\n<!--more--><br \/>\n<strong>Querida Sanga,<\/strong><\/p>\n<p>\u00c9 com grande alegria que compartilhamos a not\u00edcia da presen\u00e7a do Lama Padma Samten em Alto Para\u00edso, no per\u00edodo de 23 de janeiro a 04 de fevereiro de 2024. Estamos organizando este retiro com dedica\u00e7\u00e3o, e felicidade para receb\u00ea-los da melhor maneira poss\u00edvel. O evento ser\u00e1 dividido em tr\u00eas partes, permitindo a participa\u00e7\u00e3o tanto daqueles que podem dedicar-se ao retiro completo quanto daqueles que s\u00f3 podem se juntar nos fins de semana. A seguir, apresentamos as datas e links com mais detalhes:<\/p>\n<p><strong>1. Retiro durante a semana &#8211; <\/strong>per\u00edodos de<strong> 23 a 26 de janeiro <\/strong>e de<strong> 29 a 02 de fevereiro:<\/strong><\/p>\n<blockquote><p>Tema: <strong>Roteiro de 21 Itens<\/strong><br \/>\nEste retiro oferecer\u00e1 ensinamentos durante os dias \u00fateis pela manh\u00e3 e pr\u00e1ticas durante as tardes.<br \/>\n<a href=\"https:\/\/cebb.org.br\/es\/retiro-de-verao-alto-paraiso-roteiro-de-21-itens\/\"><em><strong>Clique aqui para se inscrever!<\/strong><\/em><\/a><\/p><\/blockquote>\n<p><strong>2. Retiro de Fim de Semana &#8211; 27 a 28 de janeiro:<br \/>\n<\/strong><\/p>\n<blockquote><p>Tema: <strong>Como Reconhecer e Dissolver Padr\u00f5es Negativos para Gerar Benef\u00edcios<\/strong><br \/>\n<a href=\"https:\/\/cebb.org.br\/es\/retiro-de-verao-alto-paraiso-como-reconhecer-e-dissolver-padroes-negativos-e-gerar-beneficios\/\"><em><strong>Clique aqui para se inscrever!<\/strong><\/em><\/a><\/p><\/blockquote>\n<p><strong>3. Retiro de Fim de Semana &#8211; 03 e 04 de fevereiro:<br \/>\n<\/strong><\/p>\n<blockquote><p>Tema: <strong>Como Pacificar a Guerra Interna e Dominar a Mente da Ilus\u00e3o de Inimigos Externos<br \/>\n<\/strong>Ser\u00e1 o encerramento do per\u00edodo de retiros.<br \/>\n<a href=\"https:\/\/cebb.org.br\/es\/retiro-de-verao-alto-paraiso-como-pacificar-as-guerras-internas-e-dominar-a-mente-da-ilusao-de-inimigos-externos\/\"><em><strong>Clique aqui para se inscrever!<\/strong><\/em><\/a><\/p><\/blockquote>\n<p><strong><br \/>\nObserva\u00e7\u00e3o importante:<\/strong> Para participantes presenciais do retiro completo, a inscri\u00e7\u00e3o \u00e9 feita atrav\u00e9s do primeiro link do <strong>&#8220;Roteiro de 21 Itens&#8221;<\/strong>. J\u00e1 para participantes online, \u00e9 necess\u00e1rio realizar a inscri\u00e7\u00e3o em cada um dos retiros para receber os links das salas do Zoom e do YouTube correspondentes.<\/p>\n<p>Foto: Lila Brenner<\/p>","protected":false},"excerpt":{"rendered":"<p>O per\u00edodo completo dos retiros ser\u00e1 de 23 a 04 de fevereiro. Voc\u00ea poder\u00e1 fazer o retiro completo ou em partes, confira!<\/p>","protected":false},"author":48,"featured_media":99204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[371,376,386,341],"tags":[],"class_list":["post-99250","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alto-paraiso","category-brasilia","category-cebb-goiania","category-eventos-passados"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/es\/lama-samten-em-alto-paraiso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"O per\u00edodo completo dos retiros ser\u00e1 de 23 a 04 de fevereiro. Voc\u00ea poder\u00e1 fazer o retiro completo ou em partes, confira!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/es\/lama-samten-em-alto-paraiso\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T19:00:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-09T10:11:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"elencezar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"elencezar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/\"},\"author\":{\"name\":\"elencezar\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/bb00a956f52df380e5f2544b21327767\"},\"headline\":\"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso\",\"datePublished\":\"2024-01-26T19:00:18+00:00\",\"dateModified\":\"2024-02-09T10:11:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg\",\"articleSection\":[\"CEBB Alto Para\u00edso\",\"CEBB Bras\u00edlia\",\"CEBB Goi\u00e2nia\",\"Eventos Passados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/\",\"name\":\"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg\",\"datePublished\":\"2024-01-26T19:00:18+00:00\",\"dateModified\":\"2024-02-09T10:11:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg\",\"width\":2560,\"height\":1700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/en\\\/lama-samten-em-alto-paraiso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/bb00a956f52df380e5f2544b21327767\",\"name\":\"elencezar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g\",\"caption\":\"elencezar\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/es\\\/author\\\/elencezar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/es\/lama-samten-em-alto-paraiso\/","og_locale":"es_ES","og_type":"article","og_title":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva","og_description":"O per\u00edodo completo dos retiros ser\u00e1 de 23 a 04 de fevereiro. Voc\u00ea poder\u00e1 fazer o retiro completo ou em partes, confira!","og_url":"https:\/\/cebb.org.br\/es\/lama-samten-em-alto-paraiso\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2024-01-26T19:00:18+00:00","article_modified_time":"2024-02-09T10:11:50+00:00","og_image":[{"width":2560,"height":1700,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg","type":"image\/jpeg"}],"author":"elencezar","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"elencezar","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/"},"author":{"name":"elencezar","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/bb00a956f52df380e5f2544b21327767"},"headline":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso","datePublished":"2024-01-26T19:00:18+00:00","dateModified":"2024-02-09T10:11:50+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg","articleSection":["CEBB Alto Para\u00edso","CEBB Bras\u00edlia","CEBB Goi\u00e2nia","Eventos Passados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/","url":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/","name":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg","datePublished":"2024-01-26T19:00:18+00:00","dateModified":"2024-02-09T10:11:50+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/11\/20230723-Retiro-de-Inverno-AP-3-scaled.jpeg","width":2560,"height":1700},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/en\/lama-samten-em-alto-paraiso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Retiros de Ver\u00e3o 2024 com Lama Padma Samten em Alto Para\u00edso"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centro de Estudios Budistas Bodisatva","description":"Budismo, meditaci\u00f3n y cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centro de Estudios Budistas Bodisatva","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/bb00a956f52df380e5f2544b21327767","name":"elencezar","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4a448ad17d8302d4ba8e5c7be6583cd414ebe1e4f0061c9944fe74729a74863a?s=96&d=mm&r=g","caption":"elencezar"},"url":"https:\/\/cebb.org.br\/es\/author\/elencezar\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/99250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/comments?post=99250"}],"version-history":[{"count":8,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/99250\/revisions"}],"predecessor-version":[{"id":99319,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/posts\/99250\/revisions\/99319"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/media\/99204"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/media?parent=99250"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/categories?post=99250"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/es\/wp-json\/wp\/v2\/tags?post=99250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}