{"id":102088,"date":"2024-05-01T08:18:16","date_gmt":"2024-05-01T11:18:16","guid":{"rendered":"https:\/\/cebb.org.br\/?p=102088"},"modified":"2024-05-20T15:50:52","modified_gmt":"2024-05-20T18:50:52","slug":"mundo-buda-darma","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/mundo-buda-darma\/","title":{"rendered":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento"},"content":{"rendered":"<p><strong>Estudo de Aprofundamento com Lama Padma Samten<br \/>\n<\/strong><strong>De 8 a 21 de maio de 2024, das 9h \u00e0s 11h (hor\u00e1rio de Bras\u00edlia)<br \/>\nTema: Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade<\/strong><br \/>\n<strong>ONLINE\u00a0<\/strong><\/p>\n<p><!--more--><\/p>\n<h3><\/h3>\n<h3>Convite do Lama Padma Samten:<\/h3>\n<blockquote><p>As palavras do Buda na forma como se apresentam em seus registros mais antigos, os Nikayas, s\u00e3o o tesouro precioso e \u00fanico que nos permite aprofundar nossa vis\u00e3o e nossas experi\u00eancias meditativas. No estudo que estaremos agora focando, examinaremos quest\u00f5es fundamentais como a pr\u00f3pria condi\u00e7\u00e3o humana, o mundo em conflito, as consequ\u00eancias das a\u00e7\u00f5es, tamb\u00e9m quem \u00e9 o Buda, seu surgimento e sua vida, o surgimento do Darma, o caminho para a realiza\u00e7\u00e3o, a felicidade nesta vida, o Darma na sociedade e na fam\u00edlia, como viver de forma elevada, como pacificar e elevar a pr\u00f3pria comunidade onde nos inserimos, como promover um renascimento elevado. Tomaremos por base para o nosso estudo o texto \u201c<strong>Nas Palavras do Buddha<\/strong>\u201d do Ven. Bukkhu Bodhi.<\/p><\/blockquote>\n<h3><\/h3>\n<h3>Programa\u00e7\u00e3o do Estudo de Aprofundamento<\/h3>\n<p><strong>Aten\u00e7\u00e3o: <\/strong>Os hor\u00e1rios e a programa\u00e7\u00e3o do estudo est\u00e3o sujeitos a altera\u00e7\u00f5es<br \/>\n<strong>Per\u00edodo:<\/strong> 8 a 21 de maio de 2024<\/p>\n<h3>Inscri\u00e7\u00e3o Online e Pr\u00e1tica de Generosidade<\/h3>\n<p><em>Sua inscri\u00e7\u00e3o e participa\u00e7\u00e3o ONLINE independem de contribui\u00e7\u00e3o financeira.<\/em> Caso aspire e lhe seja poss\u00edvel contribuir, o valor de refer\u00eancia \u00e9 R$550,00. Sua contribui\u00e7\u00e3o apoiar\u00e1 as atividades do Lama Padma Samten.<\/p>\n<p><em>A pr\u00e1tica da Dana Paramita \u2013 perfei\u00e7\u00e3o da generosidade \u2013 torna poss\u00edvel a continuidade dos ensinamentos desde os tempos do Buda. As seis paramitas \u2013 generosidade, moralidade, paz, energia constante, concentra\u00e7\u00e3o e sabedoria \u2013 inspiram a pr\u00e1tica e s\u00e3o a base geradora e sustentadora dos centros de estudos, medita\u00e7\u00e3o, acolhimento e das iniciativas de educa\u00e7\u00e3o, prote\u00e7\u00e3o ambiental, Terras Puras e Cultura de Paz da Sanga CEBB.<\/em><\/p>\n<p>&nbsp;<\/p>\n<a href=\"https:\/\/acaoparamita.com.br\/ensinamentos\/inscricao-para-o-estudo-de-aprofundamento-nossa-existencia-o-mundo-o-buda-o-darma-e-a-sociedade\/\" class=\"su-button su-button-style-default\" style=\"color:#FFFFFF;background-color:#b8190d;border-color:#94140b;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:0px 16px;font-size:13px;line-height:26px;border-color:#ce5e56;border-radius:5px;text-shadow:none\"> Fa\u00e7a sua inscri\u00e7\u00e3o ON-LINE!<\/span><\/a>\n<h3><\/h3>\n<h3>Transmiss\u00e3o ONLINE<\/h3>\n<p>O estudo ocorrer\u00e1 por transmiss\u00e3o online direta do CEBB Caminho do Meio, pelo Zoom e pelo canal Youtube do Lama Padma Samten. O link para a p\u00e1gina de acompanhamento do estudo, onde ser\u00e3o informados os links de cada per\u00edodo do estudo, ser\u00e1 enviado por um email-resposta ap\u00f3s o envio do formul\u00e1rio de inscri\u00e7\u00e3o. Caso n\u00e3o encontre o email-resposta em sua caixa de entrada, VERIFIQUE NA CAIXA DE SPAM ou em \u201cPROMO\u00c7\u00d5ES\u201d e marque como n\u00e3o-spam (caso esteja no SPAM). Pode ser \u00fatil incluir o endere\u00e7o (acaoparamita@gmail.com) na sua lista de contatos.<\/p>\n<h3><\/h3>\n<h3>Contato<\/h3>\n<p>acaoparamita@gmail.com | (51) 99799 8184 (WhatsApp) (atendimento de segunda a sexta das 13h30 \u00e0s 18h).<br \/>\nOrganiza\u00e7\u00e3o: A\u00e7\u00e3o Paramita e CEBBs Caminho do Meio, Jetavana e Akanishta (Bacupari).<\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<h4><\/h4>\n<h4>Projetos, Pr\u00e1ticas e Sonhos da Escola Caminho do Meio<\/h4>\n<p>A Escola Caminho do Meio vem acolhendo muitos alunos ao longo dos \u00faltimos 15 anos e teve a alegria de formar a 1\u00aa turma do 9\u00ba ano em 2022. Funcionando imersa em uma comunidade e em um bosque, sua abordagem pedag\u00f3gica \u00e9 centrada no cultivo do mundo interno, no favorecimento de rela\u00e7\u00f5es e na integra\u00e7\u00e3o com a natureza. Encoraja o universo daquilo que faz sentido para cada crian\u00e7a, trabalha com o brincar e a criatividade, a arte e as diferentes linguagens, e o aprendizado por projetos \u2014 cultivando uma educa\u00e7\u00e3o de mente, cora\u00e7\u00e3o, m\u00e3os e corpo inteiro. Muitos sonhos j\u00e1 foram realizados e muitos avan\u00e7os est\u00e3o por vir, convidamos voc\u00ea a fazer parte dessa rede que acredita na Educa\u00e7\u00e3o para a Felicidade, <strong><a href=\"https:\/\/escolacaminhodomeio.com.br\/apoie\/\">clique e saiba como engajar-se<\/a>.<\/strong><\/p>\n<h4><\/h4>\n<h4>Projetos e Sonhos da Bodisatva<\/h4>\n<p>A Bodisatva \u00e9 uma plataforma de comunica\u00e7\u00e3o a servi\u00e7o do <i>budismo em solo brasileiro<\/i> e tem dedicado seus esfor\u00e7os na tradu\u00e7\u00e3o e difus\u00e3o de conte\u00fados de sabedoria de linhagens aut\u00eanticas em l\u00edngua portuguesa, mas tamb\u00e9m \u00e0 publica\u00e7\u00e3o de textos produzidos por mestres e praticantes de nosso pr\u00f3prio pa\u00eds. O idealizador da Bodisatva \u00e9 o primeiro brasileiro a ser ordenado lama dentro da linhagem Nyingma do budismo tibetano, Lama Padma Samten. A partir de sua vis\u00e3o e confian\u00e7a de que os ensinamentos milenares do Buda podem melhorar nossas vidas n\u00e3o apenas individual mas coletivamente, a Bodisatva surge como esse ve\u00edculo de budismo e transforma\u00e7\u00e3o de mundo: a primeira revista de pensamento budista do Brasil, <strong><a href=\"https:\/\/bodisatva.com.br\/apoie\/\">clique e saiba como engajar-se<\/a>.<\/strong><\/p>\n<h4><\/h4>\n<h4>Projetos e Sonhos do Lama Samten<\/h4>\n<p>Uma das principais aspira\u00e7\u00f5es do Lama Samten \u00e9 apoiar os praticantes e os locais de retiros especialmente o CEBB Caminho do Meio, CEBB Bacupari e CEBB Jetavana e acolher estudantes na Escola Caminho do Meio. \u00c9 uma grande d\u00e1diva existirem espa\u00e7os de sil\u00eancio que possibilitem o aprofundamento na pr\u00e1tica de medita\u00e7\u00e3o e tamb\u00e9m surgirem praticantes com essa aspira\u00e7\u00e3o, <strong><a href=\"https:\/\/cebb.org.br\/fr\/projetos-e-sonhos-do-lama-samten\/\">clique e saiba como engajar-se<\/a>.<\/strong><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>De 8 a 21 de maio de 2024, das 9h \u00e0s 11h (hor\u00e1rio de Bras\u00edlia)<\/p>","protected":false},"author":41,"featured_media":97006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[365,377,341,344,355,364],"tags":[],"class_list":["post-102088","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-viamao","category-eventos-passados","category-lamasamten","category-pratica-on-line","category-treinamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/mundo-buda-darma\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"De 8 a 21 de maio de 2024, das 9h \u00e0s 11h (hor\u00e1rio de Bras\u00edlia)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/mundo-buda-darma\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-01T11:18:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T18:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"polliana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"polliana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/\"},\"author\":{\"name\":\"polliana\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2123fd62b5ce97d67a4cc0849bd7b645\"},\"headline\":\"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento\",\"datePublished\":\"2024-05-01T11:18:16+00:00\",\"dateModified\":\"2024-05-20T18:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/\"},\"wordCount\":842,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/capa-post-site-min.png\",\"articleSection\":[\"Agenda do Lama Padma Samten\",\"CEBB Caminho do Meio\",\"Eventos Passados\",\"Lama Padma Samten\",\"Pr\u00e1tica on-line\",\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/\",\"name\":\"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/capa-post-site-min.png\",\"datePublished\":\"2024-05-01T11:18:16+00:00\",\"dateModified\":\"2024-05-20T18:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/capa-post-site-min.png\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/capa-post-site-min.png\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/mundo-buda-darma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/2123fd62b5ce97d67a4cc0849bd7b645\",\"name\":\"polliana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g\",\"caption\":\"polliana\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/polliana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/mundo-buda-darma\/","og_locale":"fr_FR","og_type":"article","og_title":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva","og_description":"De 8 a 21 de maio de 2024, das 9h \u00e0s 11h (hor\u00e1rio de Bras\u00edlia)","og_url":"https:\/\/cebb.org.br\/fr\/mundo-buda-darma\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2024-05-01T11:18:16+00:00","article_modified_time":"2024-05-20T18:50:52+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png","type":"image\/png"}],"author":"polliana","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"polliana","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/"},"author":{"name":"polliana","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2123fd62b5ce97d67a4cc0849bd7b645"},"headline":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento","datePublished":"2024-05-01T11:18:16+00:00","dateModified":"2024-05-20T18:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/"},"wordCount":842,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png","articleSection":["Agenda do Lama Padma Samten","CEBB Caminho do Meio","Eventos Passados","Lama Padma Samten","Pr\u00e1tica on-line","Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/mundo-buda-darma\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/","url":"https:\/\/cebb.org.br\/mundo-buda-darma\/","name":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png","datePublished":"2024-05-01T11:18:16+00:00","dateModified":"2024-05-20T18:50:52+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/mundo-buda-darma\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/06\/capa-post-site-min.png","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/mundo-buda-darma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Nossa Exist\u00eancia, o Mundo, o Buda, o Darma e a Sociedade | Estudo de Aprofundamento"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/2123fd62b5ce97d67a4cc0849bd7b645","name":"polliana","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48e49773e97caa564e8e265beba0401f438954d77e33d1a2663f8eba92920800?s=96&d=mm&r=g","caption":"polliana"},"url":"https:\/\/cebb.org.br\/fr\/author\/polliana\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/102088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=102088"}],"version-history":[{"count":17,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/102088\/revisions"}],"predecessor-version":[{"id":102298,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/102088\/revisions\/102298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/97006"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=102088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=102088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=102088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}