{"id":106005,"date":"2020-08-27T11:32:49","date_gmt":"2020-08-27T14:32:49","guid":{"rendered":"https:\/\/cebb.org.br\/?p=106005"},"modified":"2024-08-29T09:27:17","modified_gmt":"2024-08-29T12:27:17","slug":"dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/","title":{"rendered":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u00c8 con grande entusiasmo che annunciamo l&#8217;inizio della serie di dialoghi preparatori per l&#8217;evento &#8220;108 Ore di Pace&#8221;, promosso dal Centro di Studi Buddisti Bodhisattva (CEBB) e dall&#8217;Istituto Caminho do Meio (ICM). Questo evento annuale, che si svolge al CEBB Caminho do Meio a Viam\u00e3o-RS ed online, mira a rafforzare le reti di interdipendenza, compassione e collaborazione in tempi di sfide sociali e ambientali.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nel primo incontro di questa serie, il nostro ospite sar\u00e0 il professor<\/span><b> Lama Padma Samten<\/b><span style=\"font-weight: 400;\">, oltre alla partecipazione speciale di:<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><b>Dr. Paolo Roberti di Sarsina, MD<\/b><\/h2>\n<p><strong>Presidente, Jamtse Ling Rim\u00e9 Center (Bologna, Italia)<br \/>\n<\/strong><em><span style=\"font-weight: 400;\">Specialista in Psichiatria e Psicoterapeuta <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/em><span style=\"font-weight: 400;\">Allievo di Ch\u00f6gyal Namkhai Norbu Rinpoche <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">Ha ricevuto insegnamenti diretti da Sua Santit\u00e0 il 14\u00ba Dalai Lama, Sua Santit\u00e0 Gongma Sakya Trichen (41\u00ba Sakya Trizin), Sua Santit\u00e0 il 12\u00ba Gyalwang Drukpa, e molti altri stimati Rinpoche e Lama. Fondatore dell&#8217;Associazione Rim\u00e9, L&#8217;unico centro italiano dedicato alla pratica non settaria del Dharma, che promuove l&#8217;unit\u00e0 tra le tradizioni buddiste. Il centro ha ricevuto il nome &#8220;Jamtse Ling&#8221; (Terra della Gentilezza Amorevole e Compassione) da Sua Santit\u00e0 il Dalai Lama. Medico specializzato in psichiatria, integra approcci convenzionali e buddisti per la guarigione. Fondatore della Fondazione per la Salutogenesi, con enfasi sulla salute e il benessere.<\/span><\/p>\n<h2><b>Jorge Koho Melo<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Monaco Soto Zen ordinato nel 2008 da Coen Roshi. Shusso in Giappone da Kuroda Roshi, Sensei nei Zen Peacemakers da Barbara Angyo Wegm\u00fcller Roshi (Svizzera) e Genro Grover Roshi (USA). Partecipa dal 2010 ai ritiri dei Zen Peacemakers nelle strade delle grandi citt\u00e0 e nei campi di concentramento di Auschwitz-Birkenau, come officiante buddista, facilitatore di Council e membro dello Staff. Attualmente ricopre il ruolo di co-direttore spirituale dell&#8217;Ordine Zen Peacemaker e lavora come consulente di Ashoka Portugal nel programma &#8220;Agenti di Cambiamento ispirati dalla fede&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><span style=\"font-weight: 400;\">Saranno condivise preziose prospettive sulla crisi climatica alla luce degli insegnamenti buddisti, affrontando come l&#8217;interconnessione e la compassione possano guidare le nostre azioni in risposta a questa emergenza globale.<\/span><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h3><em><b>Dettagli dell&#8217;Incontro<\/b><span style=\"font-weight: 400;\">:\u00a0<\/span><\/em><\/h3>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">28 agosto\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ore 10.00 (Brasilia) \/ Ore 15.00 (Roma)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Formato: Online o in presenza al CEBB CM<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><em><strong>Non \u00e8 richiesta alcuna registrazione, basta accedere a Zoom e selezionare la lingua desiderata.<\/strong><\/em><\/p>\n<p><a href=\"https:\/\/us06web.zoom.us\/j\/83868498815?pwd=CpLP5RbFclYHoFqBfidwqgpDWfMaJJ.1#succes\">https:\/\/us06web.zoom.us\/j\/83868498815?pwd=CpLP5RbFclYHoFqBfidwqgpDWfMaJJ.1#succes<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><em><b>Serie di Dialoghi Preparatori\u00a0<\/b><\/em><\/h2>\n<p><span style=\"font-weight: 400;\">Fino a dicembre, avremo incontri mensili con ospiti speciali che discuteranno diversi aspetti della crisi climatica e altre questioni rilevanti. Questi dialoghi culmineranno nell&#8217;evento &#8220;108 Ore di Pace&#8221;, che si svolger\u00e0 negli ultimi giorni dell&#8217;anno e si concluder\u00e0 il 1\u00b0 gennaio con una conferenza del nostro caro maestro Lama Padma Samten. Questa serie di dialoghi \u00e8 un&#8217;opportunit\u00e0 unica per approfondire la nostra comprensione e pratica di fronte alle sfide ambientali che affrontiamo. Contiamo sulla partecipazione di tutti per arricchire questi momenti di riflessione e apprendimento collettivo.<\/span><\/p>\n<p>Para mais informa\u00e7\u00f5es e confirma\u00e7\u00e3o de participa\u00e7\u00e3o no encontro de agosto, acesse:<\/p>\n<p><a href=\"https:\/\/108horasdepaz.com.br\/\"><span style=\"font-weight: 400;\">Per ulteriori informazioni e conferma della partecipazione all&#8217;incontro di agosto, visita <\/span><i><span style=\"font-weight: 400;\">il nostro sito web 108 Ore di Pace e guarda le registrazioni degli incontri passati<\/span><\/i><span style=\"font-weight: 400;\">.\u00a0 <\/span><\/a><\/p>\n<h3><span style=\"font-weight: 400;\"><strong>Contatto<\/strong> <\/span><\/h3>\n<h3><span style=\"font-weight: 400;\">cebbcm@gmail.com | +55 (51) 99799 8184 (WhatsApp) (assistenza dal luned\u00ec al venerd\u00ec dalle 13:30 alle 18:00) <\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La tua presenza e il tuo contributo sono una gioia per il nostro evento e per il rafforzamento della nostra comunit\u00e0!<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c8 con grande entusiasmo che annunciamo l&#8217;inizio della serie di dialoghi preparatori per l&#8217;evento &#8220;108 Ore di Pace&#8221;, promosso dal Centro di Studi Buddisti Bodhisattva (CEBB) e dall&#8217;Istituto Caminho do Meio (ICM). Questo evento annuale, che si svolge al CEBB Caminho do Meio a Viam\u00e3o-RS ed online, mira a rafforzare le reti di interdipendenza, compassione [&hellip;]<\/p>\n","protected":false},"author":79,"featured_media":105574,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[333,377,666],"tags":[674],"class_list":["post-106005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-108-horas","category-viamao","category-passados-eventos","tag-cebb-caminho-do-meio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"\u00c8 con grande entusiasmo che annunciamo l&#8217;inizio della serie di dialoghi preparatori per l&#8217;evento &#8220;108 Ore di Pace&#8221;, promosso dal Centro di Studi Buddisti Bodhisattva (CEBB) e dall&#8217;Istituto Caminho do Meio (ICM). Questo evento annuale, che si svolge al CEBB Caminho do Meio a Viam\u00e3o-RS ed online, mira a rafforzare le reti di interdipendenza, compassione [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-27T14:32:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T12:27:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coletivo Intersomos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coletivo Intersomos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/\"},\"author\":{\"name\":\"Coletivo Intersomos\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/05a696a76f72d472c540f3d7a905f39c\"},\"headline\":\"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica\",\"datePublished\":\"2020-08-27T14:32:49+00:00\",\"dateModified\":\"2024-08-29T12:27:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/\"},\"wordCount\":546,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png\",\"keywords\":[\"cebb caminho do meio\"],\"articleSection\":[\"108 horas\",\"CEBB Caminho do Meio\",\"Passados Eventos\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/\",\"name\":\"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png\",\"datePublished\":\"2020-08-27T14:32:49+00:00\",\"dateModified\":\"2024-08-29T12:27:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/05a696a76f72d472c540f3d7a905f39c\",\"name\":\"Coletivo Intersomos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"caption\":\"Coletivo Intersomos\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/coletivo-intersomos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/","og_locale":"fr_FR","og_type":"article","og_title":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva","og_description":"\u00c8 con grande entusiasmo che annunciamo l&#8217;inizio della serie di dialoghi preparatori per l&#8217;evento &#8220;108 Ore di Pace&#8221;, promosso dal Centro di Studi Buddisti Bodhisattva (CEBB) e dall&#8217;Istituto Caminho do Meio (ICM). Questo evento annuale, che si svolge al CEBB Caminho do Meio a Viam\u00e3o-RS ed online, mira a rafforzare le reti di interdipendenza, compassione [&hellip;]","og_url":"https:\/\/cebb.org.br\/fr\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2020-08-27T14:32:49+00:00","article_modified_time":"2024-08-29T12:27:17+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png","type":"image\/png"}],"author":"Coletivo Intersomos","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Coletivo Intersomos","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/"},"author":{"name":"Coletivo Intersomos","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/05a696a76f72d472c540f3d7a905f39c"},"headline":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica","datePublished":"2020-08-27T14:32:49+00:00","dateModified":"2024-08-29T12:27:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/"},"wordCount":546,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png","keywords":["cebb caminho do meio"],"articleSection":["108 horas","CEBB Caminho do Meio","Passados Eventos"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/","url":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/","name":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png","datePublished":"2020-08-27T14:32:49+00:00","dateModified":"2024-08-29T12:27:17+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2020\/08\/A-perspectiva-Budista-sobre-a-Crise-Climatica.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/dialoghi-108-ore-di-pace-la-prospettiva-buddista-sulla-crisi-climatica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Dialoghi 108 Ore di Pace \u2013 La prospettiva buddista sulla crisi climatica"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/05a696a76f72d472c540f3d7a905f39c","name":"Coletivo Intersomos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","caption":"Coletivo Intersomos"},"url":"https:\/\/cebb.org.br\/fr\/author\/coletivo-intersomos\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/106005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=106005"}],"version-history":[{"count":6,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/106005\/revisions"}],"predecessor-version":[{"id":106049,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/106005\/revisions\/106049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/105574"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=106005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=106005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=106005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}