{"id":116012,"date":"2025-07-08T09:13:55","date_gmt":"2025-07-08T12:13:55","guid":{"rendered":"https:\/\/cebb.org.br\/?p=116012"},"modified":"2026-05-06T20:51:43","modified_gmt":"2026-05-06T23:51:43","slug":"sementes-de-sanga","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/sementes-de-sanga\/","title":{"rendered":"Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as"},"content":{"rendered":"<p><em>Com grande alegria o CEBB Fortaleza oferta uma pr\u00e1tica mensal para as crian\u00e7as, no domingo, 31 de maio das 9h \u00e0s 11h, teremos nossa pr\u00f3xima pr\u00e1tica. Participe e convide todas as pessoas que possam se beneficiar!<\/em><!--more--><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<blockquote>\n<p style=\"text-align: right;\">\u201cPara n\u00f3s, adultos, \u00e9 muito dif\u00edcil ver as coisas como elas s\u00e3o de verdade.<br \/>\nN\u00f3s nos assustamos, temos medo, sofremos. Criamos fantasias e ilus\u00f5es para podermos viver a vida sem entrarmos em contato com a realidade.<br \/>\nQuando treinamos nossa mente desde crian\u00e7a, temos a oportunidade \u00fanica de desenvolvermos uma juventude e entrada na vida adulta de forma mais tranquila e menos confusa, pois permitimos que a sabedoria surja naturalmente. Podemos sentar e olhar com uma profunda sinceridade para dentro, e perceber, com isso, a interconex\u00e3o com todos os seres.\u201d<br \/>\nMonge Taik\u014d Sh\u014dei<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>A pr\u00e1tica com as crian\u00e7as \u00e9 uma brincadeira simples. Observe a respira\u00e7\u00e3o. O ar entra e sai. Apenas isso. Com a simplicidade da mente das crian\u00e7as. Num espa\u00e7o aberto, vamos respirar em sil\u00eancio. Vamos contar hist\u00f3rias, falar o que compreendemos, escutar o que o outro compreendeu. Vamos nos divertir e terminar a manh\u00e3 com um lanche coletivo.<br \/>\n&nbsp;<br \/>\nO <strong>P\u00fablico-alvo<\/strong> s\u00e3o crian\u00e7as de 6 a 12 anos, mas conseguimos ampliar essa faixa para caber menores e maiores que desejem estar presentes.Todos s\u00e3o bem vindos!<br \/>\n&nbsp;<br \/>\n<strong>ATEN\u00c7\u00c3O: Orientamos que as crian\u00e7as participem acompanhadas de seus respons\u00e1veis.<\/strong><br \/>\n&nbsp;<br \/>\n<em>Tragam um bichinho de pel\u00facia para usarmos na pr\u00e1tica e tamb\u00e9m algo bem gostoso para oferecer durante o lanche.<\/em><br \/>\n&nbsp;<br \/>\n<strong>Quando<\/strong><br \/>\n31 de maio<br \/>\n<strong>Hor\u00e1rio<\/strong><br \/>\n09h \u00e0s 11h<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Local<\/strong><\/h3>\n<p>Rua Joaquim Nabuco, 700, Meireles<br \/>\n&nbsp;<\/p>\n<h3>Contribui\u00e7\u00e3o Livre<\/h3>\n<p>As contribui\u00e7\u00f5es s\u00e3o a \u00fanica fonte para manter e cobrir as despesas dos Centros de Darma, assim como a divulga\u00e7\u00e3o dos ensinamentos e a organiza\u00e7\u00e3o de palestras e encontros. Por outro lado, elas s\u00e3o apenas sugeridas e n\u00e3o obrigat\u00f3rias, pois esperamos que as pessoas n\u00e3o encontrem nisso um obst\u00e1culo para sua participa\u00e7\u00e3o. Ao contribuir, voc\u00ea estar\u00e1 apoiando as movimenta\u00e7\u00f5es do Lama Padma Samten, do CEBB e as atividades do CEBB Fortaleza. Qualquer d\u00favida, entre em contato conosco.<\/p>\n<h3>Contatos<\/h3>\n<p>85 99991 7187 | 85 98783 7816<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/cebbfortaleza\/\">Facebook <\/a>|<a href=\"https:\/\/www.instagram.com\/cebbfortaleza\/\">Instagram<\/a> |<a href=\"https:\/\/www.youtube.com\/channel\/UCu5FM_AmP1crNO0A225i15Q\"> Youtube<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Com grande alegria o CEBB Fortaleza oferta uma pr\u00e1tica mensal para as crian\u00e7as, no domingo, 31 de maio das 9h \u00e0s 11h, teremos nossa pr\u00f3xima pr\u00e1tica. Participe e convide todas as pessoas que possam se beneficiar!<\/p>","protected":false},"author":21,"featured_media":116006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[384,335],"tags":[522],"class_list":["post-116012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cebb-fortaleza","category-cultura-de-paz","tag-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"description\" content=\"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/sementes-de-sanga\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/sementes-de-sanga\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-08T12:13:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T23:51:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1470\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"fortaleza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"fortaleza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/\"},\"author\":{\"name\":\"fortaleza\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/8645602d8100f3565fb9a9d20429c700\"},\"headline\":\"Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as\",\"datePublished\":\"2025-07-08T12:13:55+00:00\",\"dateModified\":\"2026-05-06T23:51:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/\"},\"wordCount\":402,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg\",\"keywords\":[\"Eventos\"],\"articleSection\":[\"CEBB Fortaleza\",\"Cultura de paz\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/\",\"name\":\"Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg\",\"datePublished\":\"2025-07-08T12:13:55+00:00\",\"dateModified\":\"2026-05-06T23:51:43+00:00\",\"description\":\"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg\",\"width\":1470,\"height\":980},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/sementes-de-sanga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/8645602d8100f3565fb9a9d20429c700\",\"name\":\"fortaleza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g\",\"caption\":\"fortaleza\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/fortaleza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva","description":"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/sementes-de-sanga\/","og_locale":"fr_FR","og_type":"article","og_title":"Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva","og_description":"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!","og_url":"https:\/\/cebb.org.br\/fr\/sementes-de-sanga\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2025-07-08T12:13:55+00:00","article_modified_time":"2026-05-06T23:51:43+00:00","og_image":[{"width":1470,"height":980,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg","type":"image\/jpeg"}],"author":"fortaleza","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"fortaleza","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/"},"author":{"name":"fortaleza","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/8645602d8100f3565fb9a9d20429c700"},"headline":"Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as","datePublished":"2025-07-08T12:13:55+00:00","dateModified":"2026-05-06T23:51:43+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/"},"wordCount":402,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg","keywords":["Eventos"],"articleSection":["CEBB Fortaleza","Cultura de paz"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/sementes-de-sanga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/","url":"https:\/\/cebb.org.br\/sementes-de-sanga\/","name":"Sementes de Sanga - Pr\u00e1tica para crian\u00e7as - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg","datePublished":"2025-07-08T12:13:55+00:00","dateModified":"2026-05-06T23:51:43+00:00","description":"No domingo, 31 de maio das 9h \u00e0s 11h o CEBB Fortaleza oferta uma pr\u00e1tica para as crian\u00e7as. Participe!","breadcrumb":{"@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/sementes-de-sanga\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/07\/31703318-dois-maos-segurando-flor-para-dar-flores-do-amor-amizade-ter-esperanca-bondade-sinceridade-gratis-foto.jpg","width":1470,"height":980},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/sementes-de-sanga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Sementes de Sanga &#8211; Pr\u00e1tica para crian\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/8645602d8100f3565fb9a9d20429c700","name":"fortaleza","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c762ea3e7654883fc3a7ddc57ddcb4f53dc23ebb1b4e0994894c17a89a64ab31?s=96&d=mm&r=g","caption":"fortaleza"},"url":"https:\/\/cebb.org.br\/fr\/author\/fortaleza\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/116012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=116012"}],"version-history":[{"count":20,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/116012\/revisions"}],"predecessor-version":[{"id":121928,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/116012\/revisions\/121928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/116006"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=116012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=116012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=116012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}