{"id":117136,"date":"2025-08-22T14:00:22","date_gmt":"2025-08-22T17:00:22","guid":{"rendered":"https:\/\/cebb.org.br\/?p=117136"},"modified":"2025-08-22T20:30:49","modified_gmt":"2025-08-22T23:30:49","slug":"108-budismo-sociedade-jovens","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/108-budismo-sociedade-jovens\/","title":{"rendered":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro"},"content":{"rendered":"<p><strong>S\u00e9rie Di\u00e1logos Budismo e Sociedade com Lama Padma Samten e convidados<\/strong><br \/>\n<strong><em>A Sociedade, os Jovens e o Futuro<br \/>\n<\/em><\/strong><strong>30 de agosto (s\u00e1bado), \u00e0s 16h00, no CEBB Curitiba<br \/>\nAtividade presencial e on-line<\/strong><br \/>\n<!--more--><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Mensagem do Lama sobre o encontro:<\/strong><\/p>\n<blockquote>\n<article class=\"text-token-text-primary w-full\" dir=\"auto\" data-testid=\"conversation-turn-2\" data-scroll-anchor=\"true\">\n<div class=\"text-base my-auto mx-auto py-5 [--thread-content-margin:--spacing(4)] @[37rem]:[--thread-content-margin:--spacing(6)] @[70rem]:[--thread-content-margin:--spacing(12)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:32rem] @[34rem]:[--thread-content-max-width:40rem] @[64rem]:[--thread-content-max-width:48rem] mx-auto flex max-w-(--thread-content-max-width) flex-1 text-base gap-4 md:gap-5 lg:gap-6 group\/turn-messages focus-visible:outline-hidden\" tabindex=\"-1\">\n<div class=\"group\/conversation-turn relative flex w-full min-w-0 flex-col agent-turn\">\n<div class=\"relative flex-col gap-1 md:gap-3\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-5\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"a31a1e64-239e-4c81-a10f-6311aab56a5b\" data-message-model-slug=\"gpt-4o\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[3px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark\">\n<p class=\"\" data-start=\"0\" data-end=\"656\"><i>Sentimos que o olhar dos jovens est\u00e1 mudado.<br \/>\nN\u00e3o s\u00f3 os jovens mudaram, n\u00f3s pais e amigos tamb\u00e9m sentimos que o pr\u00f3prio mundo est\u00e1 muito desafiador e demanda habilidades que j\u00e1 n\u00e3o encontramos nas institui\u00e7\u00f5es tradicionais de ensino.<br \/>\nTempos atr\u00e1s v\u00edamos a terra, a natureza como a base da resili\u00eancia, hoje vemos nossa habilidade diante do mundo virtual, do valor flutuante das coisas incluindo ai as rela\u00e7\u00f5es.<br \/>\nNeste s\u00e1bado dia 30 de agosto sentaremos calmamente, educadores, jovens, estudantes, praticantes budistas para refletir sobre nossos jovens, sobre nossas institui\u00e7\u00f5es, sobre nossas escolas e universidades, sobre nossas vidas.<\/i><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>Na s\u00e9rie\u00a0<strong>\u201cDi\u00e1logos Budismo e Sociedade\u201d<\/strong>, o Lama Padma Samten conduz conversas com convidados e tamb\u00e9m compartilha reflex\u00f5es sobre o Budismo e temas socialmente relevantes, como Educa\u00e7\u00e3o, Di\u00e1logo Inter-religioso, Economia, Cultura Contempor\u00e2nea, Psicologia, Ci\u00eancia, Ecologia, e os Povos Origin\u00e1rios, entre outros. <a href=\"https:\/\/cebb.org.br\/dialogos-budismo-sociedade\/\">Saiba mais aqui <strong><em>\u202d\u2192<\/em><\/strong><\/a><\/p>\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-021d250 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"021d250\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33290af\" data-id=\"33290af\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-adabf09 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"adabf09\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-divider\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p><strong><span class=\"OYPEnA text-decoration-none text-strikethrough-none\"><img decoding=\"async\" class=\"wp-image-113938 size-full alignleft\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/05\/Lama.png\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/05\/Lama.png 150w, https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/05\/Lama-12x12.png 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/span><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">Lama Padma Samten <\/span><\/strong><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u00e9 f<\/span><span class=\"OYPEnA text-decoration-none text-strikethrough-none\">\u00edsico pela UFRGS, Alfredo Aveline deu aulas na universidade por 20 anos. Ativista ambiental, fundou em 1986 o CEBB (Centro de Estudos Budistas Bodisatva) e largou a doc\u00eancia para dedicar-se \u00e0 espiritualidade. Em 1996 foi ordenado Lama budista por seu mestre, Chagdud Rinpoche, tibetano fundador do Templo de Tr\u00eas Coroas. Hoje, Lama Padma Samten \u2013 dedica-se \u00e0 ci\u00eancia, \u00e0 espiritualidade e ao movimento ecol\u00f3gico.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3>Convidados<\/h3>\n<p><strong><img decoding=\"async\" class=\"wp-image-117140 alignleft\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-09.31.55_bc4a6f98-300x300.jpg\" alt=\"\" width=\"165\" height=\"165\" srcset=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-09.31.55_bc4a6f98-300x300.jpg 300w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-09.31.55_bc4a6f98-169x169.jpg 169w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-09.31.55_bc4a6f98-12x12.jpg 12w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-09.31.55_bc4a6f98.jpg 640w\" sizes=\"(max-width: 165px) 100vw, 165px\" \/>Andrea Caldas<\/strong> Doutora em Educa\u00e7\u00e3o com atua\u00e7\u00e3o na educa\u00e7\u00e3o b\u00e1sica e no ensino superior. H\u00e1 32 anos \u00e9 professora do Setor de Educa\u00e7\u00e3o da UFPR na \u00e1rea de forma\u00e7\u00e3o de professores\/as e pol\u00edticas educacionais. Atualmente \u00e9 Pro Reitora de Gradua\u00e7\u00e3o e Educa\u00e7\u00e3o Profissional da UFPR.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><strong><img decoding=\"async\" class=\"alignleft wp-image-117141\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977-278x300.jpg\" alt=\"\" width=\"153\" height=\"165\" srcset=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977-278x300.jpg 278w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977-948x1024.jpg 948w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977-768x829.jpg 768w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977-11x12.jpg 11w, https:\/\/cebb.org.br\/wp-content\/uploads\/2024\/08\/Imagem-do-WhatsApp-de-2025-08-20-as-12.15.53_651e4c27-e1755722249977.jpg 1200w\" sizes=\"(max-width: 153px) 100vw, 153px\" \/>Let\u00edcia Sampaio <\/strong>Analista de dados, escritora e podcaster do &#8220;Deixe as vozes falarem&#8221; formada em Publicidade e Propaganda pelo Centro Universit\u00e1rio Univel e estudante de Big Data e Intelig\u00eancia Anal\u00edtica pela PUCPR. Praticante da Sangha de Cascavel, estudante do Lama Padma Samten.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-115580\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/06\/eliana-tavares-e1749738391228-201x300.jpg\" alt=\"\" width=\"110\" height=\"165\" srcset=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/06\/eliana-tavares-e1749738391228-201x300.jpg 201w, https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/06\/eliana-tavares-e1749738391228-8x12.jpg 8w, https:\/\/cebb.org.br\/wp-content\/uploads\/2025\/06\/eliana-tavares-e1749738391228.jpg 296w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/>Eliana Tavares<\/strong> \u00e9 professora de Lingu\u00edstica, na Universidade Federal de Rio Grande (FURG), desde 1998; fez doutorado em Neurolingu\u00edstica na UNICAMP e P\u00f3s-Doutorado em Lingu\u00edstica Cognitiva, na Universidade Cat\u00f3lica de Braga (UCP \u2013 Portugal); atualmente, faz um segundo P\u00f3s-Doc em Lingu\u00edstica, na UFRGS, no qual aprofunda os estudos sobre l\u00edngua e cogni\u00e7\u00e3o. Investiga e orienta pesquisas vinculadas \u00e0 abordagem cognitiva da significa\u00e7\u00e3o, que buscam compreender o papel da mente na rela\u00e7\u00e3o entre a l\u00edngua e o mundo. Em 2010, devido \u00e0 doen\u00e7a de Alzheimer de sua av\u00f3 materna, aproximou-se do Darma, tornando-se disc\u00edpula do Lama Samten; atualmente, tem casa no CEBB Akanishta.<\/p>\n<h3><\/h3>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<h3><span style=\"color: #ffffff;\">.<\/span><\/h3>\n<h3><strong>Inscri\u00e7\u00e3o Presencial<\/strong><\/h3>\n<p>O CEBB Curitiba fica localizado no seguinte endere\u00e7o: <strong>R. Conselheiro Carr\u00e3o, 1155. Alto da XV \u2013 Curitiba \u2013 PR<br \/>\n<\/strong><a href=\"https:\/\/forms.gle\/SKKdSh3Y6c93Aokx8\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b8190d;border-color:#94140b;border-radius:4px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:5px 14px;font-size:12px;line-height:18px;border-color:#ce5e56;border-radius:4px;text-shadow:none\"><i class=\"sui sui-map-marker\" style=\"font-size:12px;color:#FFFFFF\"><\/i> INSCRI\u00c7\u00c3O Presencial<\/span><\/a>\n<p>&nbsp;<\/p>\n<h3><strong>Pr\u00e1tica de Generosidade<\/strong><\/h3>\n<p>Sua inscri\u00e7\u00e3o e participa\u00e7\u00e3o ONLINE independem de contribui\u00e7\u00e3o financeira. Caso aspire e lhe seja poss\u00edvel contribuir, sinta-se livre para definir o valor. Como refer\u00eancia, sugerimos os valores de R$ 60,00. Sua contribui\u00e7\u00e3o apoiar\u00e1 o CEBB Caminho do Meio.<\/p>\n<blockquote><p><em>A pr\u00e1tica da Dana Paramita \u2013 perfei\u00e7\u00e3o da generosidade \u2013 torna poss\u00edvel a continuidade dos ensinamentos desde os tempos do Buda. As seis paramitas \u2013 generosidade, moralidade, paz, energia constante, concentra\u00e7\u00e3o e sabedoria \u2013 inspiram a pr\u00e1tica e s\u00e3o a base geradora e sustentadora dos centros de estudos, medita\u00e7\u00e3o, acolhimento e das iniciativas de educa\u00e7\u00e3o, prote\u00e7\u00e3o ambiental, Terras Puras e Cultura de Paz da Sanga CEBB.<\/em><\/p><\/blockquote>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h3><strong>Fa\u00e7a a sua inscri\u00e7\u00e3o aqui<\/strong><\/h3>\n<a href=\"https:\/\/caminhodomeio.org.br\/evento\/dialogos-budismo-e-sociedade-108-de-paz-jovens-e-o-futuro\/\" class=\"su-button su-button-style-flat\" style=\"color:#FFFFFF;background-color:#b8190d;border-color:#94140b;border-radius:4px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#FFFFFF;padding:5px 14px;font-size:12px;line-height:18px;border-color:#ce5e56;border-radius:4px;text-shadow:none\"><i class=\"sui sui-map-marker\" style=\"font-size:12px;color:#FFFFFF\"><\/i> INSCRI\u00c7\u00c3O ONLINE <\/span><\/a>\n<p>Ao fazer sua inscri\u00e7\u00e3o, voc\u00ea receber\u00e1 o link de acesso ao Zoom e ao Youtube (ao vivo).<\/p>\n<p>&nbsp;<\/p>\n<h3>Contato<\/h3>\n<p>Se tiver alguma d\u00favida, por favor, envie um email para <strong>acaoparamita@gmail.com <\/strong>ou entre em contato (51) 99799 8184 (apenas WhatsApp).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>30 de agosto (sexta), \u00e0s 16h00, no CEBB Curitiba<\/p>","protected":false},"author":79,"featured_media":96779,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[365,654,380,415,344],"tags":[472,482],"class_list":["post-117136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda","category-budismo-e-sociedade","category-curitiba","category-sukhavati","category-lamasamten","tag-cebb-curitiba","tag-cebb-sukhavati"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"description\" content=\"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/108-budismo-sociedade-jovens\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/108-budismo-sociedade-jovens\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-22T17:00:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-22T23:30:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Coletivo Intersomos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coletivo Intersomos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/\"},\"author\":{\"name\":\"Coletivo Intersomos\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/05a696a76f72d472c540f3d7a905f39c\"},\"headline\":\"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro\",\"datePublished\":\"2025-08-22T17:00:22+00:00\",\"dateModified\":\"2025-08-22T23:30:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/\"},\"wordCount\":732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Serie-Dialogos-new1.png\",\"keywords\":[\"Cebb Curitiba\",\"CEBB Sukhavati\"],\"articleSection\":[\"Agenda do Lama Padma Samten\",\"Budismo e Sociedade\",\"CEBB Curitiba\",\"CEBB Sukhavati\",\"Lama Padma Samten\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/\",\"name\":\"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Serie-Dialogos-new1.png\",\"datePublished\":\"2025-08-22T17:00:22+00:00\",\"dateModified\":\"2025-08-22T23:30:49+00:00\",\"description\":\"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Serie-Dialogos-new1.png\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Serie-Dialogos-new1.png\",\"width\":720,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/108-budismo-sociedade-jovens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/05a696a76f72d472c540f3d7a905f39c\",\"name\":\"Coletivo Intersomos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g\",\"caption\":\"Coletivo Intersomos\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/coletivo-intersomos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva","description":"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/108-budismo-sociedade-jovens\/","og_locale":"fr_FR","og_type":"article","og_title":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva","og_description":"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h","og_url":"https:\/\/cebb.org.br\/fr\/108-budismo-sociedade-jovens\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2025-08-22T17:00:22+00:00","article_modified_time":"2025-08-22T23:30:49+00:00","og_image":[{"width":720,"height":520,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png","type":"image\/png"}],"author":"Coletivo Intersomos","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Coletivo Intersomos","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/"},"author":{"name":"Coletivo Intersomos","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/05a696a76f72d472c540f3d7a905f39c"},"headline":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro","datePublished":"2025-08-22T17:00:22+00:00","dateModified":"2025-08-22T23:30:49+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/"},"wordCount":732,"commentCount":0,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png","keywords":["Cebb Curitiba","CEBB Sukhavati"],"articleSection":["Agenda do Lama Padma Samten","Budismo e Sociedade","CEBB Curitiba","CEBB Sukhavati","Lama Padma Samten"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/","url":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/","name":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png","datePublished":"2025-08-22T17:00:22+00:00","dateModified":"2025-08-22T23:30:49+00:00","description":"Que perspectivas de futuro se desenham para os jovens? Lama Samten e convidados em Curitiba, 30 de agosto, \u00e0s 16h","breadcrumb":{"@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2023\/05\/Serie-Dialogos-new1.png","width":720,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/108-budismo-sociedade-jovens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Di\u00e1logos Budismo e Sociedade 108 Horas de Paz | A Sociedade, os Jovens e o Futuro"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/05a696a76f72d472c540f3d7a905f39c","name":"Coletivo Intersomos","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b3268ebf7c1516b7910dc782a9ef52986a33844353256fce20260189c5f6b83?s=96&d=mm&r=g","caption":"Coletivo Intersomos"},"url":"https:\/\/cebb.org.br\/fr\/author\/coletivo-intersomos\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/117136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=117136"}],"version-history":[{"count":16,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/117136\/revisions"}],"predecessor-version":[{"id":117352,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/117136\/revisions\/117352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/96779"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=117136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=117136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=117136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}