{"id":61762,"date":"2018-11-12T16:31:56","date_gmt":"2018-11-12T18:31:56","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=61762"},"modified":"2018-11-12T16:31:56","modified_gmt":"2018-11-12T18:31:56","slug":"o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/","title":{"rendered":"O que fazer quando outras pessoas abusam de nossa generosidade?"},"content":{"rendered":"<p><!--more--><\/p>\n<blockquote><p><span style=\"color: #000000;\"><strong>Os bodisatvas n\u00e3o desistem. N\u00e3o perdem a paci\u00eancia, n\u00e3o alteram a energia, eles se movem, e o desafio deles \u00e9 atuar desse modo: n\u00e3o se perturbar, usar a\u00e7\u00e3o pacificadora, a\u00e7\u00e3o incrementadora e a\u00e7\u00e3o irada.\u00a0Quando tudo desaba, eles seguem ajudando.\u00a0 Eles n\u00e3o t\u00eam a aspira\u00e7\u00e3o pelo controle, ent\u00e3o tamb\u00e9m n\u00e3o se frustram.\u00a0\u00a0Que \u00e9 uma coisa um pouco paradoxal porque, ainda que eles tenham a energia e est\u00e3o ajudando, se aquilo fecha, eles tamb\u00e9m n\u00e3o entram em crise.<\/strong><\/span><\/p><\/blockquote>\n<p>Os bodisatvas t\u00eam energia est\u00e1vel e meios h\u00e1beis. Ent\u00e3o, se algu\u00e9m abusa, essa \u00e9 uma condi\u00e7\u00e3o natural, os seres s\u00e3o todos abusadores, porque eles s\u00e3o seres do mundo! Eles seguem por impulso, eles gostam ou n\u00e3o gostam. Eles botam aquilo na frente e v\u00e3o fazendo o que acham que t\u00eam que fazer.<br \/>\nOs beb\u00eas s\u00e3o super abusadores, eles choram na hora errada, e na hora que a gente terminou de trocar a fralda eles \u201cbrrrrummmmm&#8230;\u201d e tudo est\u00e1 sujo de novo e d\u00e1 aqueles problemas todos. Tem que trocar tudo de novo. Assim que eles sentam come\u00e7am a disparar ordens, quando come\u00e7am a engatinhar fazem tudo o que n\u00e3o devem&#8230; s\u00e3o totalmente abusadores!\u00a0 Mas se as m\u00e3es n\u00e3o forem bodisatvas e os pais n\u00e3o forem bodisatvas, eles v\u00e3o enlouquecer no meio disso. Se eles resolverem botar ordem na casa, est\u00e3o perdidos! (risos) \u00a0\u00c9 melhor n\u00e3o botar ordem, o melhor \u00e9 ter paci\u00eancia, olhar de uma forma mais elevada e absorver e neutralizar aquilo,\u00a0 \u00e9 uma a\u00e7\u00e3o acolhedora, uma a\u00e7\u00e3o inclusiva. O fato de ser abusador ou n\u00e3o, n\u00e3o \u00e9 o caso. \u00c9 saber se n\u00f3s temos condi\u00e7\u00f5es de poder absorver, ter paci\u00eancia\u00a0 e ajudar as pessoas no n\u00edvel em que elas precisam ser ajudadas. Eventualmente a gente n\u00e3o tem essa habilidade, n\u00e3o tem o meio h\u00e1bil, n\u00e3o tem a paci\u00eancia, n\u00e3o tem a estabilidade, a\u00ed n\u00f3s vamos fazer o que n\u00f3s podemos.<br \/>\nSe a gente se sentir abusado e n\u00e3o tiver um meio h\u00e1bil \u00e9 melhor se distanciar, e n\u00e3o fazer a\u00e7\u00f5es negativas a partir disso. Tamb\u00e9m \u00e9 super importante entender a nossa dificuldade, a nossa incapacidade, aspirar que a gente no futuro tenha capacidade de ajudar melhor. Ajudar tamb\u00e9m n\u00e3o \u00e9 concordar. A paci\u00eancia n\u00e3o \u00e9 concordar. A paci\u00eancia \u00e9, em primeiro lugar, a a\u00e7\u00e3o de poder, de n\u00e3o se perturbar, em segundo lugar a a\u00e7\u00e3o pacificadora do outro, a a\u00e7\u00e3o incrementadora, e a a\u00e7\u00e3o irada.\u00a0 Aquilo que precisa ser movido, no n\u00edvel que precisa ser movido, a gente move. Se n\u00e3o d\u00e1, a gente n\u00e3o move. Nem sempre a a\u00e7\u00e3o irada \u00e9 \u00fatil.Mas o bodisatva sabe que, na falta das quatro a\u00e7\u00f5es, que incluem a irada, o est\u00e1gio seguinte \u00e9 Maharaja. \u00a0Maharaja vai cobrar com carma!<br \/>\nA a\u00e7\u00e3o irada, eventualmente, consegue interromper aquilo, n\u00e3o chegar em Maharaja, n\u00e3o chegar no fruto c\u00e1rmico, n\u00e3o chegar na confus\u00e3o. Agora, se chegar na confus\u00e3o, o bodisatva n\u00e3o desiste, ele segue ajudando no n\u00edvel que d\u00e1. \u00a0\u00c0s vezes a gente n\u00e3o tem o meio h\u00e1bil, n\u00e3o tem como evitar. As pessoas t\u00eam estruturas c\u00e1rmicas e t\u00eam autonomia. Se elas quiserem, elas conseguem ultrapassar a boa vontade do outro e criar o que quiserem criar, elas criam, elas t\u00eam essa habilidade, \u00a0elas t\u00eam a natureza de Buda, elas t\u00eam a liberdade de construir as coisas como elas querem. Mas os bodisatvas n\u00e3o desistem. N\u00e3o perdem a paci\u00eancia, n\u00e3o alteram a energia, eles se movem, e o desafio deles \u00e9 atuar desse modo: n\u00e3o se perturbar, usar a\u00e7\u00e3o pacificadora, a\u00e7\u00e3o incrementadora e a\u00e7\u00e3o irada. <strong>Quando tudo desaba, eles seguem ajudando.\u00a0 Eles n\u00e3o t\u00eam a aspira\u00e7\u00e3o pelo controle, ent\u00e3o tamb\u00e9m n\u00e3o se frustram.\u00a0<\/strong> Que \u00e9 uma coisa um pouco paradoxal porque, ainda que eles tenham a energia e est\u00e3o ajudando, se aquilo fecha, eles tamb\u00e9m n\u00e3o entram em crise.<br \/>\nV\u00e1rias vezes, observei os tibetanos, como S.S.\u00a0 Sakya Trizin contando as trag\u00e9dias do Tibete. Eu olhava para o rosto dele, ele n\u00e3o se perturbava! Da mesma forma Chagdud Rinpoche, vi v\u00e1rios mestres narrando, ainda que eles tenham passado por situa\u00e7\u00f5es super dif\u00edceis, contradit\u00f3rias, abusivas&#8230; eu n\u00e3o via a sensa\u00e7\u00e3o de censura, de criminaliza\u00e7\u00e3o do outro, n\u00e3o via isso.\u00a0 <strong>Eles est\u00e3o vendo a inevitabilidade da aus\u00eancia de harmonia no mundo.<\/strong> <strong>Eles n\u00e3o t\u00eam a ilus\u00e3o da harmonia, nem tampouco a ilus\u00e3o de que eles agindo, ou os Budas agindo, o mundo vai endireitar. Eles n\u00e3o esperam isso.<\/strong> No CEBB, a gente espera isso&#8230; (risos) \u00a0Esse \u00e9 o aspecto relativo, a gente fala em Terra Pura, reencantamento, a gente imagina que a gente pode melhorar.\u00a0\u00a0 E eu acredito que deva melhorar. Mas n\u00e3o acho que seja absoluto, isso n\u00e3o \u00e9 absoluto.\u00a0 E tamb\u00e9m n\u00e3o \u00e9 o caso de a gente se frustrar, a gente anda, a gente vai sempre encontrando as contradi\u00e7\u00f5es inerentes \u00e0s coisas.\u00a0 Mas a gente n\u00e3o deixa de se mover, a gente segue se movendo. Isso, por uma parte, \u00a0\u00e9 um treinamento nosso, de outra parte isso melhora mesmo.\u00a0 O mundo melhora. A gente pode melhorar o mundo.<br \/>\nEu acho bonito, \u00e0s vezes, esses relatos, como o do Kentaro Sugao contando para n\u00f3s sobre o templo l\u00e1 de Terra Pura. Os velhos japoneses est\u00e3o bem velhos agora.\u00a0 Eles eram jovens japoneses. Agora eles s\u00e3o velhos japoneses, e o templo vai ficando vazio, porque as novas gera\u00e7\u00f5es seguem um pouco, mas n\u00e3o seguem.\u00a0 Ent\u00e3o o budismo \u00e9tnico japon\u00eas vai decaindo. No entanto, os velhos seguem indo l\u00e1. Se n\u00f3s estiv\u00e9ssemos l\u00e1, a gente ia pensar: \u201cPara a\u00ed, a gente tem que fazer alguma coisa!\u201d. Eles est\u00e3o seguindo e v\u00e3o at\u00e9 o fim. Isso \u00e9 bonito de ver, esse natural ocaso, o sol estava se pondo. Mas eles, dignamente, vivem o final do tempo. Acho isso bonito. Sem controle, sem a frustra\u00e7\u00e3o de dizer: \u201cn\u00f3s fizemos errado\u201d. N\u00e3o. N\u00f3s seguimos os mestres, n\u00f3s fizemos aquilo, e agora o tempo \u00e9 diferente, ent\u00e3o isso termina conosco. N\u00f3s estamos indo, vai terminar. Eles n\u00e3o t\u00eam a sensa\u00e7\u00e3o de que o Budismo termina, o Buda ultrapassa aquilo tudo. Ent\u00e3o, essa confian\u00e7a \u00e9 considerada uma grande qualidade. <strong>Essa confian\u00e7a no Buda, nesse n\u00edvel, mesmo que o Budismo desapare\u00e7a, ele ressurge, porque a gente tem a clareza do que \u00e9 a lucidez da mente. A lucidez da mente termina retornando, ressurge, \u00e9 completamente certo!<\/strong><br \/>\n<em>Ensinamentos oferecidos por Lama Padma Samten em 11\/09\/2018.\u00a0<\/em><br \/>\n<em>Transcri\u00e7\u00e3o: Clarissa Gleich<\/em><br \/>\n<em>Edi\u00e7\u00e3o: Stela Santin\u00a0<\/em><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":119,"featured_media":61763,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[352],"tags":[],"class_list":["post-61762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perguntas-respostas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-12T18:31:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"O que fazer quando outras pessoas abusam de nossa generosidade?\",\"datePublished\":\"2018-11-12T18:31:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/\"},\"wordCount\":1194,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/buda-1.jpg\",\"articleSection\":[\"Perguntas e respostas\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/\",\"name\":\"O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/buda-1.jpg\",\"datePublished\":\"2018-11-12T18:31:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/buda-1.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/buda-1.jpg\",\"width\":800,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que fazer quando outras pessoas abusam de nossa generosidade?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/","og_locale":"fr_FR","og_type":"article","og_title":"O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva","og_url":"https:\/\/cebb.org.br\/fr\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2018-11-12T18:31:56+00:00","og_image":[{"width":800,"height":450,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/"},"author":{"name":"","@id":""},"headline":"O que fazer quando outras pessoas abusam de nossa generosidade?","datePublished":"2018-11-12T18:31:56+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/"},"wordCount":1194,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg","articleSection":["Perguntas e respostas"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/","url":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/","name":"O que fazer quando outras pessoas abusam de nossa generosidade? - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg","datePublished":"2018-11-12T18:31:56+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/11\/buda-1.jpg","width":800,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/o-que-fazer-quando-outras-pessoas-abusam-de-nossa-generosidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"O que fazer quando outras pessoas abusam de nossa generosidade?"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"","url":"https:\/\/cebb.org.br\/fr\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/61762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/119"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=61762"}],"version-history":[{"count":0,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/61762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/61763"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=61762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=61762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=61762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}