{"id":68803,"date":"2018-02-21T17:52:23","date_gmt":"2018-02-21T20:52:23","guid":{"rendered":"http:\/\/www.cebb.org.br\/?p=68803"},"modified":"2025-05-31T23:52:33","modified_gmt":"2025-06-01T02:52:33","slug":"retiro-aberto-e-retiro-fechado-no-cebb-darmata","status":"publish","type":"post","link":"https:\/\/cebb.org.br\/fr\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/","title":{"rendered":"Retiro Aberto e Retiro Fechado no CEBB Darmata"},"content":{"rendered":"<p>Conhe\u00e7a como funcionam os retiros aberto e fechado do CEBB Darmata.<\/p>\n<h4 style=\"text-align: center;\"><!--more--><\/h4>\n<p style=\"text-align: left;\">\n<p>O programa e os retiros s\u00e3o dedicados ao aprofundamento da pr\u00e1tica formal de medita\u00e7\u00e3o, do estudo dos ensinamentos e o treinamento da vis\u00e3o e a\u00e7\u00e3o dentro da Mandala, com acompanhamento individual realizado por tutores do Programa de Forma\u00e7\u00e3o de Facilitadores do CEBB. Depois de ouvir, entender e praticar mais extensamente o <strong>roteiro de 21 itens do treinamento do CEBB<\/strong>, o interesse de aprofundar as contempla\u00e7\u00f5es em um local silencioso, distante dos centros urbanos, pode brotar.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p><strong><img decoding=\"async\" class=\"size-full wp-image-83907 aligncenter\" src=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2021\/05\/linha-com-no-infinto.png\" alt=\"\" width=\"150\" height=\"23\" \/><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Programa e Retiros no CEBB Darmata<\/strong><\/h3>\n<p>&nbsp;<\/p>\n<p>O CEBB Darmata \u00e9 um dos centros de retiros mais antigos do Nordeste e consolidado dentro da rede dos CEBB&#8217;s. Desta forma, muitos praticantes o procuram para aprofundar seus estudos e pr\u00e1tica de medita\u00e7\u00e3o, com uma rotina favor\u00e1vel e retirados de suas atividades cotidianas.<br \/>\nPara participar \u00e9 importante que a pessoa j\u00e1 esteja frequentando algum dos nossos centros urbanos ou rurais (<a href=\"https:\/\/cebb.org.br\/fr\/centros-no-brasil\/\" target=\"_blank\" rel=\"noopener\">verifique se existe algum CEBB perto de voc\u00ea<\/a>), esteja engajada em uma pr\u00e1tica regular, integrando minimamente a pr\u00e1tica em seu cotidiano.<\/p>\n<p>Durante a estadia no CEBB a pessoa ser\u00e1 acompanhada pelo tutor ou tutora local, ter\u00e1 acesso a todas as atividades no templo, hospedagem em alojamento coletivo e alimenta\u00e7\u00e3o vegetariana. Em cada caso ser\u00e1 combinado o formato da pr\u00e1tica e a rotina espec\u00edfica junto com a coordena\u00e7\u00e3o e tutores do local, e a contribui\u00e7\u00e3o financeira do praticante para viabilizar o processo.<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Formatos<\/strong><\/h3>\n<p>Dependendo das condi\u00e7\u00f5es locais e da maturidade na pr\u00e1tica, essa inser\u00e7\u00e3o pode se dar em quatro formatos b\u00e1sicos:<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Retiros de instru\u00e7\u00f5es:<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Finais de semana com palestras e oficinas, abertos a todos os interessados em conhecer sobre o budismo, medita\u00e7\u00e3o e suas pr\u00e1ticas. Qualquer pessoa pode participar. Informa\u00e7\u00f5es e inscri\u00e7\u00f5es s\u00e3o publicadas na p\u00e1gina do\u00a0<a href=\"https:\/\/cebb.org.br\/fr\/centros\/pe\/darmata\/\" target=\"_blank\" rel=\"noopener\">CEBB Darmata<\/a>\u00a0um m\u00eas antes do evento. As atualiza\u00e7\u00f5es tamb\u00e9m podem ser acompanhadas no nosso\u00a0<a href=\"https:\/\/www.instagram.com\/cebbdarmata\/\" target=\"_blank\" rel=\"noopener\">instagram<\/a>.<\/li>\n<p>&nbsp;<\/p>\n<\/ul>\n<ul>\n<li><strong>Retiro Aberto:\u00a0<\/strong>Nesta modalidade o praticante fica imerso no dia-a-dia do CEBB, com apoio da comunidade de moradores, e pode se dedicar ao aprofundamento da pr\u00e1tica formal de medita\u00e7\u00e3o, ao estudo dos ensinamentos e ao treinamento da vis\u00e3o e a\u00e7\u00e3o dentro da Mandala. O retiro aberto \u00e9 indicado para pessoas que j\u00e1 conhecem um pouco o Darma e j\u00e1 vem h\u00e1 algum tempo praticando a medita\u00e7\u00e3o.<\/li>\n<\/ul>\n<p style=\"text-align: center;\">\u00a0<a href=\"https:\/\/cebb.org.br\/fr\/retiro-aberto-darmata\/\" target=\"_blank\" rel=\"noopener\">Para mais informa\u00e7\u00f5es e inscri\u00e7\u00e3o no\u00a0<strong>retiro aberto<\/strong>\u00a0clique aqui!<\/a><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Retiro Fechado:\u00a0<\/strong>Indicado para quem j\u00e1 est\u00e1 sendo acompanhado por um tutor ou tutora do CEBB. Nesta modalidade o praticante se retira, por um tempo determinado, do conv\u00edvio no cotidiano da comunidade de moradores. Assim, ele faz suas pr\u00e1ticas, come e dorme em uma das casas destinadas aos retiros fechados. Nesta modalidade de retiro \u00e9 dedicada ao aprofundamento da pr\u00e1tica do roteiro de 21 Itens oferecido pelo Lama Samten como um meio de realiza\u00e7\u00e3o direta da vis\u00e3o de Sabedoria. Para que haja um bom aproveitamento do tempo, o roteiro dever\u00e1 ser previamente estudado e praticado com o acompanhamento de um tutor. O tutor tamb\u00e9m ser\u00e1 respons\u00e1vel por ajudar o praticante a planejar seu retiro, definindo quando e por quanto tempo ser\u00e1, e tamb\u00e9m os pontos do roteiro a serem aprofundados.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"https:\/\/cebb.org.br\/fr\/retiro-fechado-darmata\/\" target=\"_blank\" rel=\"noopener\">Para mais informa\u00e7\u00f5es e inscri\u00e7\u00e3o no\u00a0<strong>retiro fechado<\/strong>\u00a0clique aqui!<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><center><\/center>Esses formatos podem se misturar ou se alternar numa mesma vinda, a partir do que for combinado em cada caso.<br \/>\nQue muitos seres possam se beneficiar!<\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Local<\/strong><\/h3>\n<p><strong>CEBB Darmata<\/strong>, Fazenda Nossa Senhora, Zona Rural de Timba\u00faba-PE.<\/p>\n<p><iframe \n  src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3956.0938287868953!2d-35.3118207!3d-7.454871499999999!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x7ac79505b7a9249%3A0x343b724dcefa2852!2sCEBB+Darmata!5e0!3m2!1spt-BR!2sbr!4v1439314261298\"\n  width=\"400\"\n  height=\"300\"\n  style=\"border:0;\"\n  allowfullscreen=\"\"\n  loading=\"lazy\"\n  referrerpolicy=\"no-referrer-when-downgrade\"><br \/>\n<\/iframe><\/p>\n<p>Mais informa\u00e7\u00f5es de como chegar na p\u00e1gina\u00a0<a href=\"https:\/\/cebb.org.br\/fr\/como-chegar-ao-darmata\/\">http:\/\/www.cebb.org.br\/como-chegar-ao-darmata\/<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>Contato<\/strong><\/h3>\n<p>Whatsapp: (81) 99229.2904 | Email: retiros.cebbdarmata@gmail.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Conhe\u00e7a como funcionam os retiros aberto e fechado do CEBB Darmata.<\/p>","protected":false},"author":97,"featured_media":65124,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[382,351,364],"tags":[],"class_list":["post-68803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-darmata","category-pe","category-treinamento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cebb.org.br\/fr\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"og:description\" content=\"Conhe\u00e7a como funcionam os retiros aberto e fechado do CEBB Darmata.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cebb.org.br\/fr\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/\" \/>\n<meta property=\"og:site_name\" content=\"Centro de Estudos Budistas Bodisatva\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/cebb108\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-21T20:52:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-01T02:52:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1505\" \/>\n\t<meta property=\"og:image:height\" content=\"849\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admincebb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admincebb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/\"},\"author\":{\"name\":\"admincebb\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/b3e274b0b565c77848134d6f13b973b9\"},\"headline\":\"Retiro Aberto e Retiro Fechado no CEBB Darmata\",\"datePublished\":\"2018-02-21T20:52:23+00:00\",\"dateModified\":\"2025-06-01T02:52:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/\"},\"wordCount\":644,\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cebbdarmata-e1552339609820.jpg\",\"articleSection\":[\"CEBB Darmata\",\"PE\",\"Treinamento em vis\u00e3o e medita\u00e7\u00e3o\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/\",\"name\":\"Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cebbdarmata-e1552339609820.jpg\",\"datePublished\":\"2018-02-21T20:52:23+00:00\",\"dateModified\":\"2025-06-01T02:52:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cebbdarmata-e1552339609820.jpg\",\"contentUrl\":\"https:\\\/\\\/cebb.org.br\\\/wp-content\\\/uploads\\\/2018\\\/02\\\/cebbdarmata-e1552339609820.jpg\",\"width\":1505,\"height\":849},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cebb.org.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retiro Aberto e Retiro Fechado no CEBB Darmata\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#website\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"description\":\"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten\",\"publisher\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cebb.org.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#organization\",\"name\":\"Centro de Estudos Budistas Bodisatva\",\"url\":\"https:\\\/\\\/cebb.org.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"contentUrl\":\"http:\\\/\\\/18.230.164.79\\\/wp-content\\\/uploads\\\/2011\\\/03\\\/logosalvador-peq-e1660064979551.jpg\",\"width\":280,\"height\":231,\"caption\":\"Centro de Estudos Budistas Bodisatva\"},\"image\":{\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/cebb108\",\"https:\\\/\\\/www.instagram.com\\\/cebbcaminhodomeio\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cebb.org.br\\\/#\\\/schema\\\/person\\\/b3e274b0b565c77848134d6f13b973b9\",\"name\":\"admincebb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g\",\"caption\":\"admincebb\"},\"url\":\"https:\\\/\\\/cebb.org.br\\\/fr\\\/author\\\/admincebb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cebb.org.br\/fr\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/","og_locale":"fr_FR","og_type":"article","og_title":"Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva","og_description":"Conhe\u00e7a como funcionam os retiros aberto e fechado do CEBB Darmata.","og_url":"https:\/\/cebb.org.br\/fr\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/","og_site_name":"Centro de Estudos Budistas Bodisatva","article_publisher":"https:\/\/pt-br.facebook.com\/cebb108","article_published_time":"2018-02-21T20:52:23+00:00","article_modified_time":"2025-06-01T02:52:33+00:00","og_image":[{"width":1505,"height":849,"url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg","type":"image\/jpeg"}],"author":"admincebb","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admincebb","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#article","isPartOf":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/"},"author":{"name":"admincebb","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/b3e274b0b565c77848134d6f13b973b9"},"headline":"Retiro Aberto e Retiro Fechado no CEBB Darmata","datePublished":"2018-02-21T20:52:23+00:00","dateModified":"2025-06-01T02:52:33+00:00","mainEntityOfPage":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/"},"wordCount":644,"publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"image":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg","articleSection":["CEBB Darmata","PE","Treinamento em vis\u00e3o e medita\u00e7\u00e3o"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/","url":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/","name":"Retiro Aberto e Retiro Fechado no CEBB Darmata - Centro de Estudos Budistas Bodisatva","isPartOf":{"@id":"https:\/\/cebb.org.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#primaryimage"},"image":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#primaryimage"},"thumbnailUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg","datePublished":"2018-02-21T20:52:23+00:00","dateModified":"2025-06-01T02:52:33+00:00","breadcrumb":{"@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#primaryimage","url":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg","contentUrl":"https:\/\/cebb.org.br\/wp-content\/uploads\/2018\/02\/cebbdarmata-e1552339609820.jpg","width":1505,"height":849},{"@type":"BreadcrumbList","@id":"https:\/\/cebb.org.br\/retiro-aberto-e-retiro-fechado-no-cebb-darmata\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cebb.org.br\/"},{"@type":"ListItem","position":2,"name":"Retiro Aberto e Retiro Fechado no CEBB Darmata"}]},{"@type":"WebSite","@id":"https:\/\/cebb.org.br\/#website","url":"https:\/\/cebb.org.br\/","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","description":"Budismo, medita\u00e7\u00e3o e cultura de paz | Lama Padma Samten","publisher":{"@id":"https:\/\/cebb.org.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cebb.org.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cebb.org.br\/#organization","name":"Centre d\u2019\u00c9tudes Bouddhistes Bodisatva (CEBB)","url":"https:\/\/cebb.org.br\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/","url":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","contentUrl":"http:\/\/18.230.164.79\/wp-content\/uploads\/2011\/03\/logosalvador-peq-e1660064979551.jpg","width":280,"height":231,"caption":"Centro de Estudos Budistas Bodisatva"},"image":{"@id":"https:\/\/cebb.org.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/cebb108","https:\/\/www.instagram.com\/cebbcaminhodomeio\/"]},{"@type":"Person","@id":"https:\/\/cebb.org.br\/#\/schema\/person\/b3e274b0b565c77848134d6f13b973b9","name":"admincebb","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5359476d548defdffdf8d0aa219a355e585f3afdba74733fd236eb023d00f048?s=96&d=mm&r=g","caption":"admincebb"},"url":"https:\/\/cebb.org.br\/fr\/author\/admincebb\/"}]}},"_links":{"self":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/68803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/users\/97"}],"replies":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/comments?post=68803"}],"version-history":[{"count":18,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/68803\/revisions"}],"predecessor-version":[{"id":115227,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/posts\/68803\/revisions\/115227"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media\/65124"}],"wp:attachment":[{"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/media?parent=68803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/categories?post=68803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cebb.org.br\/fr\/wp-json\/wp\/v2\/tags?post=68803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}